{"id":242834,"date":"2019-12-10T00:00:00","date_gmt":"2019-12-10T00:00:00","guid":{"rendered":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/"},"modified":"2021-11-05T17:51:45","modified_gmt":"2021-11-05T17:51:45","slug":"cartons-increase-turnover-2","status":"publish","type":"post","link":"https:\/\/www.procarton.com\/it\/cartons-increase-turnover-2\/","title":{"rendered":"I cartoni aumentano il fatturato!"},"content":{"rendered":"<p><strong>Il modo in cui i prodotti influenzano l'acquirente dipende non da ultimo dal materiale di imballaggio. Lo dimostra uno studio condotto dall'Universit\u00e0 Justus Liebig di Giessen per conto dell'Associazione tedesca dell'industria del cartone (FFI) e di Pro Carton, che ora \u00e8 disponibile sia in inglese che nell'originale tedesco.  Pro Carton ne ha parlato con la dottoressa Melanie Bowen dell'Universit\u00e0, che ha supervisionato lo studio dal punto di vista scientifico.<\/strong><\/p>\n<p><em>Pro Carton: Qual \u00e8 stato il punto di partenza della ricerca?<\/em><\/p>\n<p>Melanie Bowen: \"Il fatturato del commercio al dettaglio di prodotti biologici e il fatturato complessivo dei prodotti biologici continuano ad aumentare. Ci sono sempre pi\u00f9 prodotti che vengono venduti nei negozi biologici e ci sono sempre pi\u00f9 marchi specializzati in alimenti biologici, che naturalmente vogliono trasmettere al consumatore l'idea di sostenibilit\u00e0 e consapevolezza ambientale.<\/p>\n<p>Ma \u00e8 chiaro che molti alimenti e molti prodotti sono ancora confezionati in plastica. Ci siamo chiesti perch\u00e9, qual \u00e8 il motivo e se l'imballaggio sostenibile in cartone non abbia effettivamente un'influenza positiva sulla percezione dei prodotti.\"<\/p>\n<p><em>Come \u00e8 progettato lo studio?<\/em><\/p>\n<p>\"Lo studio \u00e8 stato impostato in modo tale da selezionare nove categorie di prodotti in consultazione con la FFI e Pro Carton. Per ognuna di queste categorie, abbiamo generato quattro immagini di prodotto che raffigurano il prodotto in confezione di cartone e in confezione di plastica, e il prodotto in forma biologica e in qualit\u00e0 convenzionale, rispettivamente.<\/p>\n<p>A ciascuno dei partecipanti allo studio \u00e8 stata poi mostrata l'immagine di un prodotto di una categoria, ad esempio biscotti biologici in confezione di cartone. Ai partecipanti \u00e8 stato poi chiesto di rispondere a domande sul prodotto e sulla confezione\".<\/p>\n<p><em>Quali sono i principali risultati di questo studio? <\/em><\/p>\n<p>\"I risultati principali sono che l'imballaggio e il materiale di confezionamento hanno un impatto sulla percezione del prodotto. Da un lato, i consumatori - in questo caso i partecipanti al nostro studio - hanno sempre percepito l'imballaggio in cartone come migliore; migliore in termini di qualit\u00e0, migliore in termini di sostenibilit\u00e0 e anche migliore nella loro valutazione complessiva.<\/p>\n<p>Ma non solo, i partecipanti percepiscono anche un miglioramento del prodotto. I prodotti biologici confezionati in cartone sono sempre stati considerati migliori, pi\u00f9 sostenibili e di qualit\u00e0 superiore. Ci\u00f2 significa che l'imballaggio in cartone ha effettivamente un'influenza positiva sulla percezione del prodotto\".<\/p>\n<p><em>Qual \u00e8 la sua conclusione personale da questo studio? <\/em><\/p>\n<p>\"Ho trovato lo studio in s\u00e9 molto sorprendente. Semplicemente confezionando i prodotti in modo diverso, si pu\u00f2 avere un impatto positivo sulla percezione del prodotto da parte del consumatore.  Il fatto \u00e8 che il packaging sostenibile valorizza il prodotto e quindi i consumatori lo acquisteranno pi\u00f9 spesso\".<\/p>\n<p>&nbsp;<\/p>\n<p>Steffen Schnizer, portavoce del Consiglio della FFI, ha commentato lo studio attuale: \"Purtroppo il contributo dell'imballaggio alla comunicazione \u00e8 ancora sottovalutato. Il presente studio dimostra che il cartone valorizza i prodotti biologici. Una strategia di prodotto sostenibile \u00e8 meglio accettata dai consumatori se comprende anche l'imballaggio\".<\/p>\n<p>Horst Bittermann, presidente di Pro Carton, fa un ulteriore passo avanti: \"Siamo convinti che nel prossimo futuro nell'industria prevarr\u00e0 la product stewardship, ossia la responsabilit\u00e0 complessiva per un prodotto in ogni fase del suo ciclo di vita. Soprattutto, l'imballaggio non deve lasciare impronte nell'ambiente e deve quindi essere biodegradabile\".<\/p>\n<p><em>La versione inglese pu\u00f2 essere trovata <a href=\"https:\/\/www.procarton.com\/publication-news\/publications\">qui.<\/a><\/em><\/p>\n<p><em>Per vedere il video dell'intervista, clicca sulla miniatura qui sotto:<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Il modo in cui i prodotti influenzano l'acquirente dipende non da ultimo dal materiale di imballaggio. Questo \u00e8 dimostrato da uno studio condotto dall'Universit\u00e0 Justus Liebig di Giessen.<\/p>","protected":false},"author":1,"featured_media":242749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[51],"class_list":["post-242834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-other","tag-studies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartons increase turnover! - Pro Carton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.procarton.com\/it\/cartons-increase-turnover-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartons increase turnover! - Pro Carton\" \/>\n<meta property=\"og:description\" content=\"How products affect the buyer depends not least on the packaging material. This is shown by a study conducted by the Justus Liebig University in Giessen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.procarton.com\/it\/cartons-increase-turnover-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Carton\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/procartondesignaward\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-10T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-05T17:51:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/Melanie-Bowen_600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"esterling@admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:site\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"esterling@admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/\"},\"author\":{\"name\":\"esterling@admin\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\"},\"headline\":\"Cartons increase turnover!\",\"datePublished\":\"2019-12-10T00:00:00+00:00\",\"dateModified\":\"2021-11-05T17:51:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/\"},\"wordCount\":558,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Melanie-Bowen_600.jpg\",\"keywords\":[\"Studies\"],\"articleSection\":[\"Other\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/\",\"name\":\"Cartons increase turnover! - Pro Carton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Melanie-Bowen_600.jpg\",\"datePublished\":\"2019-12-10T00:00:00+00:00\",\"dateModified\":\"2021-11-05T17:51:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Melanie-Bowen_600.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Melanie-Bowen_600.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/cartons-increase-turnover-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.procarton.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartons increase turnover!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"name\":\"Pro Carton\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\",\"name\":\"ProCarton\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"width\":422,\"height\":519,\"caption\":\"ProCarton\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/procartondesignaward\\\/\",\"https:\\\/\\\/x.com\\\/pro_carton\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\",\"name\":\"esterling@admin\",\"sameAs\":[\"https:\\\/\\\/www.procarton.com\"],\"url\":\"https:\\\/\\\/www.procarton.com\\\/it\\\/author\\\/esterlingadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I cartoni aumentano il fatturato! - Cartone Pro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.procarton.com\/it\/cartons-increase-turnover-2\/","og_locale":"it_IT","og_type":"article","og_title":"Cartons increase turnover! - Pro Carton","og_description":"How products affect the buyer depends not least on the packaging material. This is shown by a study conducted by the Justus Liebig University in Giessen.","og_url":"https:\/\/www.procarton.com\/it\/cartons-increase-turnover-2\/","og_site_name":"Pro Carton","article_publisher":"https:\/\/www.facebook.com\/procartondesignaward\/","article_published_time":"2019-12-10T00:00:00+00:00","article_modified_time":"2021-11-05T17:51:45+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/Melanie-Bowen_600.jpg","type":"image\/jpeg"}],"author":"esterling@admin","twitter_card":"summary_large_image","twitter_creator":"@pro_carton","twitter_site":"@pro_carton","twitter_misc":{"Scritto da":"esterling@admin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/#article","isPartOf":{"@id":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/"},"author":{"name":"esterling@admin","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251"},"headline":"Cartons increase turnover!","datePublished":"2019-12-10T00:00:00+00:00","dateModified":"2021-11-05T17:51:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/"},"wordCount":558,"commentCount":0,"publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"image":{"@id":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/Melanie-Bowen_600.jpg","keywords":["Studies"],"articleSection":["Other"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.procarton.com\/cartons-increase-turnover-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/","url":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/","name":"I cartoni aumentano il fatturato! - Cartone Pro","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/#primaryimage"},"image":{"@id":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/Melanie-Bowen_600.jpg","datePublished":"2019-12-10T00:00:00+00:00","dateModified":"2021-11-05T17:51:45+00:00","breadcrumb":{"@id":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.procarton.com\/cartons-increase-turnover-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/#primaryimage","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/Melanie-Bowen_600.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/Melanie-Bowen_600.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.procarton.com\/cartons-increase-turnover-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.procarton.com\/"},{"@type":"ListItem","position":2,"name":"Cartons increase turnover!"}]},{"@type":"WebSite","@id":"https:\/\/www.procarton.com\/es\/#website","url":"https:\/\/www.procarton.com\/es\/","name":"Pro Carton","description":"","publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.procarton.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.procarton.com\/es\/#organization","name":"ProCarton","url":"https:\/\/www.procarton.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","width":422,"height":519,"caption":"ProCarton"},"image":{"@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/procartondesignaward\/","https:\/\/x.com\/pro_carton"]},{"@type":"Person","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251","name":"esterling@admin","sameAs":["https:\/\/www.procarton.com"],"url":"https:\/\/www.procarton.com\/it\/author\/esterlingadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/posts\/242834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/comments?post=242834"}],"version-history":[{"count":1,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/posts\/242834\/revisions"}],"predecessor-version":[{"id":265810,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/posts\/242834\/revisions\/265810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/media\/242749"}],"wp:attachment":[{"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/media?parent=242834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/categories?post=242834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/tags?post=242834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}