{"id":242154,"date":"2016-01-29T00:00:00","date_gmt":"2016-01-29T00:00:00","guid":{"rendered":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/"},"modified":"2021-11-07T15:59:56","modified_gmt":"2021-11-07T15:59:56","slug":"10-top-trends-of-2016-the-internet-world-of-packaging","status":"publish","type":"post","link":"https:\/\/www.procarton.com\/it\/10-top-trends-of-2016-the-internet-world-of-packaging\/","title":{"rendered":"10 Top Trends del 2016: Il mondo dell'imballaggio su Internet"},"content":{"rendered":"<p><strong>Il mondo \u00e8 un grande centro commerciale. I POS sono ovunque. Siamo nel mezzo di una rivoluzione. Internet sta semplicemente cambiando tutto: design, marketing e strutture commerciali. Questo ha anche conseguenze di vasta portata per il packaging, che sta giocando un ruolo ancora pi\u00f9 importante, in quanto sta diventando l'elemento centrale dell'esperienza di acquisto.  Pro Carton ha esaminato le 10 tendenze internazionali pi\u00f9 importanti.<\/strong><\/p>\n<p>Tre sono gli sviluppi attuali che determinano queste tendenze: innanzitutto, i clienti impiegano ancora troppo tempo per inserire i dati. I nuovi servizi di indirizzamento stanno trasformando questo aspetto in un ricordo del passato. Presto baster\u00e0 il nome del destinatario per far arrivare il regalo. Alibaba ha gi\u00e0 fatto un passo avanti: nel marzo 2015 l'amministratore delegato Jack Ma ha mostrato una tecnologia che permetter\u00e0 agli utenti di pagare \"in stile selfie\" utilizzando il riconoscimento facciale dello smartphone.<\/p>\n<p>In secondo luogo, le cose annunciate da tempo stanno diventando realt\u00e0: gli elettrodomestici stanno diventando un'interfaccia per la vendita al dettaglio. Il servizio di rifornimento Amazon Dash consente gi\u00e0 di riordinare i detersivi tramite un sensore della lavatrice. Sono in corso partnership corrispondenti con i produttori.  Gartner, una societ\u00e0 di consulenza statunitense, stima che le macchine collegate a Internet genereranno un fatturato di 263 miliardi di dollari nel 2020.<\/p>\n<p>Terzo: la consegna si velocizzer\u00e0 notevolmente. Nel Regno Unito Argos offre la consegna in giornata 7 giorni su 7 per piccoli ordini a 90% di famiglie. Amazon UK consegna prodotti alimentari e bevande in localit\u00e0 selezionate in meno di un'ora per 6,99 GBP, o gratuitamente per gli utenti Prime, con un minimo di spesa. Ocado offre consegne in giornata e in fasce orarie, coprendo 70% di famiglie.<\/p>\n<p>In generale, le informazioni diventano sempre pi\u00f9 trasparenti e i servizi sempre pi\u00f9 veloci. Ci\u00f2 si ripercuote sull'intera Supply Chain.<\/p>\n<h3>1. Design: la fine dell'autenticit\u00e0<\/h3>\n<p>L'autenticit\u00e0 dimostrativa appartiene al passato. Parole come artigianale \"hanno perso ogni significato, valore, verit\u00e0 e peso descrittivo\", afferma Martin Raymond, caporedattore di The Future Laboratory, una societ\u00e0 di consulenza londinese che si occupa di lifestyle e consumer insight. Ci\u00f2 che conta \u00e8 la vera autenticit\u00e0, che non ha bisogno di spiegazioni. Pi\u00f9 importante di un aspetto \"autentico\" \u00e8 una prestazione convincente che combini qualit\u00e0 tecnica e origine naturale. Il contraccolpo anti-autenticit\u00e0 \"non significa che i prodotti non possano essere autentici, artigianali o fatti a mano\", afferma Raymond, ma \"come nel vero lusso, questi vantaggi devono essere evidenti, manifesti e impliciti\".<\/p>\n<h3>2. Design: comunicazioni chiare<\/h3>\n<p>Con il crescente numero di indicazioni sulla confezione che competono per l'attenzione degli acquirenti, i consumatori chiedono pi\u00f9 informazioni su ci\u00f2 che stanno acquistando, ma cercano meno disordine sulla confezione che confonda le loro decisioni di acquisto. Questo \u00e8 forse pi\u00f9 evidente che nel cibo, dove il 58% dei consumatori britannici controlla le informazioni sugli ingredienti sulla confezione del prodotto e il 76% \u00e8 preoccupato per l'uso di conservanti artificiali. Informazioni chiare e concise sugli ingredienti, gli attributi funzionali del prodotto, o anche la convenienza e la sicurezza devono essere comunicate con totale trasparenza - una responsabilit\u00e0 chiave che i marchi e i consumatori stanno ponendo sul packaging.<\/p>\n<h3>3. Marketing: la naturalezza diventa la misura di tutte le cose<\/h3>\n<p>Il naturale \u00e8 tornato - mentre i consumatori ansiosi rifiutano un sistema industriale che appare sempre pi\u00f9 tossico e dannoso per la salute, si rivolgono ai prodotti naturali come soluzione. Cresciuti con la cultura digitale, non vedono pi\u00f9 la natura e la tecnologia come reciprocamente esclusive, e stanno combinando i migliori aspetti di entrambe per costruire stili di vita New Natural. Dieta, bellezza, benessere, mente, corpo, fitness: tutto \u00e8 visto dal consumatore come un unico grande ecosistema da mantenere. I marchi, una volta giudicati per la loro desiderabilit\u00e0 e per i loro prodotti, ora vengono giudicati per i loro sistemi di valori, per il fatto che sono innovatori, per il fatto che promettono di cambiare il mondo.<\/p>\n<h3>4. Marketing: essere onesti conta<\/h3>\n<p>Avere una missione sociale non \u00e8 pi\u00f9 un bonus ma un'aspettativa fondamentale tra i consumatori, in particolare i millennial. Un recente sondaggio sugli atteggiamenti dei consumatori nei confronti dei marchi ha scoperto che l'88 % dei millennial britannici e statunitensi e della generazione X crede che i marchi debbano fare pi\u00f9 bene, non solo \"meno male\". Ora le aziende stanno portando il bene sociale a proporzioni epiche. Lego, consapevole del numero sempre crescente di giocattoli di plastica nelle discariche, ha investito 150 milioni di dollari nella ricerca sui materiali sostenibili. Ikea sta superando la maggior parte dei governi con i suoi investimenti nella sostenibilit\u00e0. Il rivenditore svedese di articoli per la casa ha promesso di spendere 1 miliardo di euro in energie rinnovabili. Come ha detto il luminare della tecnologia Biz Stone durante il South by Southwest Interactive 2015, \"Il futuro del marketing \u00e8 la filantropia\".<\/p>\n<h3>5. Marketing: i prodotti sostenibili sono preferiti<\/h3>\n<p>La sostenibilit\u00e0 \u00e8 una tendenza futura fondamentale. Pi\u00f9 crescono le preoccupazioni per il nostro pianeta, meno possibilit\u00e0 ci sono per Plastic &amp; Co. \u00c8 vero che molti consumatori non hanno il budget extra per spendere di pi\u00f9 per la sostenibilit\u00e0. Tuttavia, il 63% dei consumatori statunitensi ha dichiarato che gli imballaggi riutilizzabili e riutilizzabili sono un fattore chiave di acquisto che vedono come un altro anello della lunga e complessa catena del packaging verde. Quando il prezzo del prodotto e la qualit\u00e0 percepita del prodotto sono uguali, i consumatori si rivolgeranno sempre pi\u00f9 a questi attributi ecologici e di uso alternativo come fattore di acquisto decisivo. In futuro, i marchi non possono permettersi di ignorarlo.<\/p>\n<h3>6. Marketing: il cervello rivela i suoi segreti<\/h3>\n<p>Il neuromarketing - una parola d'ordine da anni nel mondo delle agenzie - sta finalmente entrando nel regno della scienza seria e delle applicazioni reali. Uno studio pubblicato nell'edizione di settembre 2015 della rivista Social Cognitive and Affective Neuroscience ha scoperto che i ricercatori sono stati in grado di prevedere con precisione i risultati su larga scala di una campagna antifumo misurando le risposte del cervello utilizzando una macchina fMRI (fMRT, tomografia a risonanza magnetica funzionale). Rispetto ai metodi tradizionali, i dati del cervello hanno pi\u00f9 che raddoppiato la capacit\u00e0 dei ricercatori di prevedere le risposte alla campagna antifumo - un risultato enormemente significativo e senza precedenti per uno studio del genere.<\/p>\n<h3>7. Commercio: i tre pilastri della crescita<\/h3>\n<p>La crescita del commercio al dettaglio si basa su tre pilastri: Internet, Discount e Convenience. I grandi volumi e gli articoli da banco vengono acquistati principalmente via Internet e nei discount. L'IGD prevede che l'online sar\u00e0 il segmento del mercato grocery del Regno Unito in pi\u00f9 rapida crescita nei prossimi cinque anni, con un valore quasi raddoppiato da 8,9 miliardi di sterline nell'aprile 2015 a 17,2 miliardi di sterline entro l'aprile 2020. I piccoli prodotti di uso quotidiano continueranno a essere acquistati nel negozio all'angolo. James Walton di IGD: \"Le nuove aperture potrebbero essere pi\u00f9 piccole dei soliti 3.000 metri quadrati, con micro-negozi di circa 1.000 metri quadrati. Questi negozi sono gi\u00e0 diffusi in altre parti del mondo (Hong Kong, Giappone), ma il loro successo richiede una logistica avanzata, un assortimento intelligente e capacit\u00e0 di gestione dello spazio\". I micro-negozi offrono anche una piattaforma per un'altra tendenza chiave: l'\"ibridazione\" del retail. Questa utilizza i negozi fisici per creare un ponte tra le operazioni reali e quelle digitali, ad esempio offrendo punti di ritiro per gli ordini online.<\/p>\n<h3>8. Imballaggio: spazio pubblicitario per una pronta distribuzione<\/h3>\n<p>Il commercio al dettaglio ha bisogno di confezioni pronte per la distribuzione, di dimensioni diverse, in grado di svolgere perfettamente le proprie funzioni in tutti i canali e di pubblicizzare i prodotti nei punti vendita, ovunque essi si trovino. Nel frattempo, 39% dei consumatori britannici vorrebbero vedere una gamma pi\u00f9 ampia di bottiglie pi\u00f9 piccole di bevande alcoliche. Come dimostra il 50% dei consumatori di snack salutistici che si dichiarano disposti a provare un nuovo prodotto se \u00e8 disponibile in una piccola confezione di prova, con l'aumento del portafoglio prodotti dei marchi, la capacit\u00e0 di raggiungere i consumatori in usi unici e mutevoli significa che i proprietari dei marchi devono offrire una maggiore gamma di formati di confezioni, sia pi\u00f9 grandi che pi\u00f9 piccole. Nel 2016, a seguito di importanti strategie di ridimensionamento come quelle attuate da Kellogg's nel 2015, se i proprietari dei marchi vogliono superare la crescente mancanza di fedelt\u00e0 al marchio da parte dei consumatori, devono creare e fornire confezioni che i consumatori considerino della giusta dimensione per loro stessi, per le loro famiglie e per i loro usi mutevoli.<\/p>\n<h3>9. Imballaggio: il collegamento diretto<\/h3>\n<p>C'\u00e8 una rivoluzione nel packaging mobile-engaged. Le interazioni mobili rappresenteranno 64 centesimi di ogni dollaro americano speso nei negozi al dettaglio entro la fine del 2016. Ma a differenza della precedente generazione di packaging mobile-enabled - che comprendeva goffi codici QR e di testo, cos\u00ec come esperienze di realt\u00e0 aumentata spesso deludenti - questa volta i proprietari di marchi stanno sfruttando la comunicazione a corto raggio (NFC) e il bluetooth a bassa energia (BLE) come tecnologie di coinvolgimento primario per mantenere la promessa che molti impegni mobili di prima generazione non hanno fatto o non hanno potuto fare. Andando avanti, mentre i marchi chiedono a gran voce modi innovativi per coinvolgere e connettersi con gli acquirenti, l'ambiente mobile diventer\u00e0 la nuova prima linea nella battaglia per conquistare il cuore, la mente e il portafoglio dei consumatori.<\/p>\n<h3>10. Imballaggio: una rivoluzione della stampa digitale<\/h3>\n<p>Le capacit\u00e0 uniche della stampa digitale hanno catturato l'attenzione di rivenditori, proprietari di marchi e trasformatori di imballaggi in tutto il mondo. Portata alla ribalta del mainstream globale dall'enorme successo della campagna \"Share a Coke\" di Coca-Cola, la stampa digitale sta catturando l'attenzione dei marchi creando opportunit\u00e0 per coinvolgere i consumatori a livello locale, personale o addirittura emotivo. Un millennial statunitense su cinque \u00e8 alla ricerca di confezioni personalizzate e quasi un quarto dei consumatori cinesi dichiara che pagherebbe di pi\u00f9 per avere confezioni di bibite personalizzate. La stampa digitale \u00e8 quindi destinata a crescere ben oltre la quota di 10% del mercato degli imballaggi che si stima rappresenti attualmente. Mintel ritiene che il 2016 rappresenter\u00e0 il punto di svolta per la stampa digitale di imballaggi, in quanto i marchi e i trasformatori di imballaggi inizieranno a non utilizzare il digitale principalmente per le edizioni limitate e la personalizzazione, ma a sfruttare i vantaggi economici e di velocit\u00e0 di commercializzazione per la decorazione di imballaggi tradizionali.<\/p>\n<p>\"Come potete vedere, l'imballaggio si trova di fronte a una serie di prospettive interessanti, nel senso che dobbiamo essere assolutamente pronti per i desideri e le esigenze future dei consumatori e del commercio al dettaglio\", afferma Roland Rex, Presidente di Pro Carton. \"L'intero settore del cartone e dell'astuccio \u00e8 ben attrezzato per affrontare queste sfide e siamo ansiosi di affrontare i compiti che ci attendono, poich\u00e9 l'imballaggio si assume una responsabilit\u00e0 ancora maggiore nell'ambito della sostenibilit\u00e0. Vediamo uno sviluppo dinamico sorprendente per il packaging in generale e attendiamo con ansia le novit\u00e0 e i progressi futuri in collaborazione con l'intera Supply Chain.\"<\/p>\n<p>&nbsp;<\/p>\n<p>Fonti:<\/p>\n<p><a href=\"http:\/\/www.euromonitor.com\" target=\"_blank\" rel=\"noopener\">www.euromonitor.com<br \/>\n<\/a><a href=\"http:\/\/www.thefuturelaboratory.com\" target=\"_blank\" rel=\"noopener\">www.thefuturelaboratory.com<br \/>\n<\/a><a href=\"http:\/\/www.gartner.com\" target=\"_blank\" rel=\"noopener\">www.gartner.com<br \/>\n<\/a><a href=\"http:\/\/igd.com\" target=\"_blank\" rel=\"noopener\">igd.com<br \/>\n<\/a><a href=\"http:\/\/www.jwtintelligence.com\" target=\"_blank\" rel=\"noopener\">www.jwtintelligence.com<br \/>\n<\/a><a href=\"http:\/\/www.mintel.com\" target=\"_blank\" rel=\"noopener\">www.mintel.com<br \/>\n<\/a><a href=\"http:\/\/trendbuero.com\" target=\"_blank\" rel=\"noopener\">trendbuero.com<br \/>\n<\/a><a href=\"http:\/\/www.trendwatching.com\" target=\"_blank\" rel=\"noopener\">www.trendwatching.com<br \/>\n<\/a><a href=\"http:\/\/www.zukunftsinstitut.de\" target=\"_blank\" rel=\"noopener\">www.zukunftsinstitut.de<\/a><\/p>\n<p>Immagini: <a href=\"http:\/\/igd.com\" target=\"_blank\" rel=\"noopener\">igd.com<\/a>, <a href=\"http:\/\/www.jwtintelligence.com\" target=\"_blank\" rel=\"noopener\">jwtintelligence.com<\/a>, <a href=\"http:\/\/onethatmatters.com\">onethatmatters.com<\/a>, <a href=\"http:\/\/www.jwtintelligence.com\" target=\"_blank\" rel=\"noopener\">jwtintelligence.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Il mondo \u00e8 un grande centro commerciale. Il POS \u00e8 ovunque. Pro Carton ha esaminato le 10 tendenze internazionali pi\u00f9 importanti.<\/p>","protected":false},"author":1,"featured_media":242155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[45],"class_list":["post-242154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-other","tag-experts-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 Top Trends of 2016: The Internet World of Packaging - Pro Carton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.procarton.com\/it\/10-top-trends-of-2016-the-internet-world-of-packaging\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 Top Trends of 2016: The Internet World of Packaging - Pro Carton\" \/>\n<meta property=\"og:description\" content=\"The world is one big shopping centre. POS is everywhere. Pro Carton has looked at the 10 most important international trends.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.procarton.com\/it\/10-top-trends-of-2016-the-internet-world-of-packaging\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Carton\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/procartondesignaward\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-29T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-07T15:59:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/trendss.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"esterling@admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:site\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"esterling@admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/\"},\"author\":{\"name\":\"esterling@admin\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\"},\"headline\":\"10 Top Trends of 2016: The Internet World of Packaging\",\"datePublished\":\"2016-01-29T00:00:00+00:00\",\"dateModified\":\"2021-11-07T15:59:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/\"},\"wordCount\":1633,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/trendss.jpg\",\"keywords\":[\"Experts\"],\"articleSection\":[\"Other\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/\",\"name\":\"10 Top Trends of 2016: The Internet World of Packaging - Pro Carton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/trendss.jpg\",\"datePublished\":\"2016-01-29T00:00:00+00:00\",\"dateModified\":\"2021-11-07T15:59:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/trendss.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/trendss.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/10-top-trends-of-2016-the-internet-world-of-packaging\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.procarton.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 Top Trends of 2016: The Internet World of Packaging\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"name\":\"Pro Carton\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\",\"name\":\"ProCarton\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"width\":422,\"height\":519,\"caption\":\"ProCarton\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/procartondesignaward\\\/\",\"https:\\\/\\\/x.com\\\/pro_carton\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\",\"name\":\"esterling@admin\",\"sameAs\":[\"https:\\\/\\\/www.procarton.com\"],\"url\":\"https:\\\/\\\/www.procarton.com\\\/it\\\/author\\\/esterlingadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le 10 principali tendenze del 2016: Il mondo Internet dell'imballaggio - Pro Carton","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.procarton.com\/it\/10-top-trends-of-2016-the-internet-world-of-packaging\/","og_locale":"it_IT","og_type":"article","og_title":"10 Top Trends of 2016: The Internet World of Packaging - Pro Carton","og_description":"The world is one big shopping centre. POS is everywhere. Pro Carton has looked at the 10 most important international trends.","og_url":"https:\/\/www.procarton.com\/it\/10-top-trends-of-2016-the-internet-world-of-packaging\/","og_site_name":"Pro Carton","article_publisher":"https:\/\/www.facebook.com\/procartondesignaward\/","article_published_time":"2016-01-29T00:00:00+00:00","article_modified_time":"2021-11-07T15:59:56+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/trendss.jpg","type":"image\/jpeg"}],"author":"esterling@admin","twitter_card":"summary_large_image","twitter_creator":"@pro_carton","twitter_site":"@pro_carton","twitter_misc":{"Scritto da":"esterling@admin","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/#article","isPartOf":{"@id":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/"},"author":{"name":"esterling@admin","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251"},"headline":"10 Top Trends of 2016: The Internet World of Packaging","datePublished":"2016-01-29T00:00:00+00:00","dateModified":"2021-11-07T15:59:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/"},"wordCount":1633,"commentCount":0,"publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"image":{"@id":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/trendss.jpg","keywords":["Experts"],"articleSection":["Other"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/","url":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/","name":"Le 10 principali tendenze del 2016: Il mondo Internet dell'imballaggio - Pro Carton","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/#primaryimage"},"image":{"@id":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/trendss.jpg","datePublished":"2016-01-29T00:00:00+00:00","dateModified":"2021-11-07T15:59:56+00:00","breadcrumb":{"@id":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/#primaryimage","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/trendss.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/trendss.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.procarton.com\/10-top-trends-of-2016-the-internet-world-of-packaging\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.procarton.com\/"},{"@type":"ListItem","position":2,"name":"10 Top Trends of 2016: The Internet World of Packaging"}]},{"@type":"WebSite","@id":"https:\/\/www.procarton.com\/es\/#website","url":"https:\/\/www.procarton.com\/es\/","name":"Pro Carton","description":"","publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.procarton.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.procarton.com\/es\/#organization","name":"ProCarton","url":"https:\/\/www.procarton.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","width":422,"height":519,"caption":"ProCarton"},"image":{"@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/procartondesignaward\/","https:\/\/x.com\/pro_carton"]},{"@type":"Person","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251","name":"esterling@admin","sameAs":["https:\/\/www.procarton.com"],"url":"https:\/\/www.procarton.com\/it\/author\/esterlingadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/posts\/242154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/comments?post=242154"}],"version-history":[{"count":1,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/posts\/242154\/revisions"}],"predecessor-version":[{"id":266149,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/posts\/242154\/revisions\/266149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/media\/242155"}],"wp:attachment":[{"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/media?parent=242154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/categories?post=242154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.procarton.com\/it\/wp-json\/wp\/v2\/tags?post=242154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}