{"id":275301,"date":"2022-03-10T08:38:50","date_gmt":"2022-03-10T08:38:50","guid":{"rendered":"https:\/\/www.procarton.com\/?p=275301"},"modified":"2022-03-14T08:44:55","modified_gmt":"2022-03-14T08:44:55","slug":"2022-packaging-trends","status":"publish","type":"post","link":"https:\/\/www.procarton.com\/fr\/2022-packaging-trends\/","title":{"rendered":"Tendances en mati\u00e8re d'emballage pour 2022"},"content":{"rendered":"<div class=\"av-animated-generic top-to-bottom flex_column av_two_third  flex_column_div av-zero-column-padding first  avia-builder-el-0  el_before_av_one_third  avia-builder-el-first\" style='border-radius:0px; '>\n<section class=\"av_textblock_section\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" >\n<div class='avia_textblock'   itemprop=\"text\" >\n<div id=\"wrap_all\">\n<p><strong>Que disent les agences de tendances internationales \u00e0 propos de l'ann\u00e9e 2022 ? Pro Carton a compil\u00e9 les pr\u00e9visions les plus importantes pour le commerce de d\u00e9tail, les marques et les emballages. La fusion du r\u00e9el et du num\u00e9rique continue de progresser, ce qui aura un impact important sur l'emballage. Il ne devra plus seulement exceller en rayon et devra \u00e9galement assumer beaucoup plus de responsabilit\u00e9s en ligne. <\/strong><\/p>\n<p>Bon nombre des tendances abord\u00e9es ici ne sont pas nouvelles en termes d'approche, mais cette ann\u00e9e, elles atteindront un nouveau niveau de qualit\u00e9. \"Les gens recherchent des solutions qui m\u00e8nent \u00e0 un avenir positif. Nous en avons une : Le carton\", d\u00e9clare Winfried M\u00fchling, directeur g\u00e9n\u00e9ral de Pro Carton.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>La num\u00e9risation : Nouvelles dimensions<\/strong><\/p>\n<p><strong>NOUVEAU en 2022 : La num\u00e9risation se radicalise et touche vraiment tous les domaines. Les choses r\u00e9elles sont reproduites sur Internet, et en plus il y a la r\u00e9alit\u00e9 augment\u00e9e et la gamification. Les emballages doivent proposer des offres correspondantes. <\/strong><\/p>\n<p>La num\u00e9risation fera encore un grand pas en avant en 2022. Non seulement les d\u00e9taillants sur Internet cr\u00e9ent de v\u00e9ritables magasins, mais les magasins r\u00e9els sont \u00e9galement recr\u00e9\u00e9s num\u00e9riquement. En janvier, Samsung a ouvert une r\u00e9plique virtuelle de son magasin phare \u00e0 New York. En juillet 2021, la marque de luxe Fendi a ouvert un flagship num\u00e9rique \u00e0 360 degr\u00e9s bas\u00e9 sur son magasin de la 57e rue \u00e0 New York, offrant aux visiteurs des visites virtuelles. Herm\u00e8s a ouvert des flagships num\u00e9riques \u00e0 Singapour, aux \u00c9mirats arabes unis et en Tha\u00eflande.<\/p>\n<p>C'est l\u00e0 que le m\u00e9tavers entre en jeu. Les codes figurant sur les emballages doivent conduire \u00e0 des informations et \u00e0 des exp\u00e9riences d'utilisation compl\u00e8tes :<\/p>\n<ol>\n<li>La r\u00e9alit\u00e9 augment\u00e9e va ouvrir de nouveaux espaces. Non seulement le monde de la publicit\u00e9 y passera le plus clair de son temps, mais l'information, le divertissement, le plaisir et la stimulation feront de plus en plus partie du produit et de l'emballage lui-m\u00eame.<\/li>\n<li>Comme les gens conversent de plus en plus via WeChat, WhatsApp et Line, les marques se jettent \u00e9galement sur ces plateformes de chat pour \u00e9tablir des relations plus personnelles avec des groupes de consommateurs individuels. L'emballage personnalis\u00e9 pourrait \u00eatre l'une des nombreuses petites r\u00e9compenses offertes aux participants.<\/li>\n<li>Le jeu et la consommation fusionnent de mani\u00e8re transparente : \"La croissance du jeu en tant que plateforme marketing est unique\", d\u00e9clare Grant Paterson, responsable du jeu et des e-sports chez Wunderman Thompson. \"Nous parlons du jeu comme du c\u0153ur d'un nouveau paradigme de consommation\".<\/li>\n<\/ol>\n<p><a href=\"http:\/\/wundermanthompson.com\/expertise\/intelligence\">wundermanthompson.com\/expertise\/intelligence<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Consommateurs : Regagner la confiance perdue<\/strong><\/p>\n<p><strong>NOUVEAU en 2022 : Le blanchiment \u00e9cologique a fait payer un lourd tribut \u00e0 la confiance des consommateurs. Pour regagner la confiance perdue, des mesures de communication tr\u00e8s concr\u00e8tes et faciles \u00e0 suivre sont n\u00e9cessaires. L'emballage doit avoir un design qui renforce la confiance.<\/strong><\/p>\n<p>Alors que 60 % des consommateurs interrog\u00e9s dans le cadre de l'enqu\u00eate Voice of the Consumer Lifestyles Survey 2021 d'Euromonitor International ont d\u00e9clar\u00e9 avoir le sentiment de pouvoir faire une diff\u00e9rence dans le monde par leurs choix et leurs actions, seuls un peu plus de 10 % des entreprises ont communiqu\u00e9 avec succ\u00e8s des informations sur la durabilit\u00e9, selon l'enqu\u00eate Voice of the Industry Sustainability Survey 2021 du m\u00eame institut.<\/p>\n<p>\"Depuis trop longtemps, l'industrie de la publicit\u00e9 se soustrait \u00e0 l'examen de son r\u00f4le dans la crise climatique\", d\u00e9clare Robbie Gillett d'Adfree Cities. \"Qu'il s'agisse d'utiliser les meilleures cr\u00e9ations pour promouvoir des produits \u00e0 forte intensit\u00e9 de carbone, de faire du greenwash trompeur pour les grandes compagnies p\u00e9troli\u00e8res, ou de remplir nos espaces publics d'\u00e9crans publicitaires \u00e9nergivores, le rouleau compresseur des relations publiques polluantes doit cesser.\"<\/p>\n<p>Les marques devront travailler davantage pour fournir aux consommateurs des informations fiables et \u00e9tablir leur authenticit\u00e9. Un emballage clair et bien structur\u00e9 peut les y aider.<\/p>\n<p><a href=\"http:\/\/www.euromonitor.com\">www.euromonitor.com<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Les marques : Presque une question de foi<\/strong><\/p>\n<p><strong>NOUVEAU en 2022 : Pour la premi\u00e8re fois, la qualit\u00e9 des produits n'est pas aussi importante que le fait qu'ils conviennent \u00e0 votre style de vie. La d\u00e9cision pour un produit devient une question de foi. L'emballage doit adopter les symboles du groupe cible et r\u00e9pondre \u00e0 ses besoins. Cons\u00e9quence logique : un m\u00eame produit n'aura pas toujours le m\u00eame emballage.<\/strong><\/p>\n<p>77 % des consommateurs dans le monde attendent un soutien des marques en temps de crise. La durabilit\u00e9 ne suffit pas ; les gens veulent qu'on s'adresse \u00e0 eux de mani\u00e8re active. En 2022, les marques devront cibler l'exp\u00e9rience individuelle plut\u00f4t que de se concentrer sur les indicateurs d\u00e9mographiques traditionnels.<\/p>\n<p>Les nouvelles r\u00e8gles d'attraction ont chang\u00e9 la fa\u00e7on dont les produits arrivent sur le march\u00e9. Alors qu'auparavant, les d\u00e9partements de R&amp;D et de marketing \u00e9taient responsables du succ\u00e8s des produits, celui-ci est d\u00e9sormais souvent orchestr\u00e9 par des influenceurs qui construisent d'abord l'audience, puis d\u00e9veloppent les produits appropri\u00e9s. Le march\u00e9 de l'appartenance et des personnes partageant les m\u00eames id\u00e9es redivise le march\u00e9 des produits et des services.<\/p>\n<p><a href=\"http:\/\/www.trendwatching.com\/22-trends-for-2022\">www.trendwatching.com\/22-trends-for-2022<\/a><\/p>\n<p><a href=\"http:\/\/trendbuero.com\">trendbuero.com<\/a> Tendances \u00e0 surveiller en 2022<\/p>\n<p>La m\u00e9gatendance de la personnalisation met en \u00e9vidence les attentes de plus en plus \u00e9gocentriques des consommateurs, notamment des biens de consommation hautement personnalisables et personnalis\u00e9s. Cela inclut une culture visuelle qui donne la priorit\u00e9 \u00e0 l'expression de soi sur les autres en ligne. La composition de nos \"marques\" personnelles influence tout ce que nous faisons et consommons.<\/p>\n<p><a href=\"http:\/\/www.euromonitor.com\">www.euromonitor.com<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Le commerce de d\u00e9tail : Le meilleur de tout<\/strong><\/p>\n<p><strong>Nouveaut\u00e9 2022 : le d\u00e9veloppement de la gamme de produits n'a pas suivi le rythme des besoins des clients ; il y a un grand besoin de rattraper le retard en termes de durabilit\u00e9 r\u00e9elle et d'\u00e9liminer activement les produits et emballages non durables. Pour la premi\u00e8re fois, la pr\u00e9sence num\u00e9rique est devenue au moins aussi importante que la pr\u00e9sence r\u00e9elle.<\/strong><\/p>\n<p>Une part importante du secteur du commerce de d\u00e9tail est pass\u00e9e au num\u00e9rique et le restera. Selon une \u00e9tude r\u00e9alis\u00e9e en juillet 2021 par Wunderman Thompson Data, 81 % des consommateurs du monde entier estiment d\u00e9sormais que la pr\u00e9sence num\u00e9rique d'une marque est aussi importante que sa pr\u00e9sence en magasin, ce qui incite les marques \u00e0 accro\u00eetre leur pr\u00e9sence en ligne et \u00e0 cr\u00e9er des magasins phares virtuels.<\/p>\n<p><a href=\"http:\/\/wundermanthompson.com\/expertise\/intelligence\">wundermanthompson.com\/expertise\/intelligence<\/a><\/p>\n<p>L'engagement en faveur de la durabilit\u00e9 continue de cro\u00eetre. Un Allemand sur trois est pr\u00eat \u00e0 payer davantage pour des produits durables. C'est ce qui ressort d'une enqu\u00eate men\u00e9e par le cabinet de conseil en gestion Simon-Kucher &amp; Partners. Les jeunes, en particulier, sont pr\u00eats \u00e0 payer plus cher pour avoir la conscience tranquille. Les Allemands qui sont pr\u00eats \u00e0 payer plus cher pour des produits plus durables accepteraient des co\u00fbts suppl\u00e9mentaires de 18 % en moyenne.<\/p>\n<p><a href=\"http:\/\/www.heise.de\">www.heise.de<\/a><\/p>\n<p>\"Le secteur du commerce de d\u00e9tail a encore du retard \u00e0 rattraper en termes de mise en \u0153uvre. Les possibilit\u00e9s sont nombreuses pour les entreprises de vente au d\u00e9tail en particulier\", d\u00e9clare Andreas Stein, expert en commerce de d\u00e9tail au sein du cabinet de conseil TCS. \"La durabilit\u00e9 ne se limite pas \u00e0 la r\u00e9duction des \u00e9missions de CO2 gr\u00e2ce \u00e0 un contr\u00f4le des b\u00e2timents et des v\u00e9hicules \u00e9conomes en \u00e9nergie ou \u00e0 l'optimisation des flux de marchandises. Les consommateurs et les entreprises elles-m\u00eames veulent plus de transparence\", ajoute M. Stein. Les emballages devraient aider les consommateurs de mani\u00e8re beaucoup plus active \u00e0 choisir les bons produits.<\/p>\n<p><a href=\"http:\/\/www.absatzwirtschaft.de\">www.absatzwirtschaft.de<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Emballage : Recyclable et compostable<\/strong><\/p>\n<p><strong>Nouveaut\u00e9 2022 : Le plastique est l'ennemi num\u00e9ro un, m\u00eame si cela n'est pas toujours justifi\u00e9. Ceux qui utilisent du plastique doivent bien le justifier. Les emballages ne doivent laisser aucune trace dans la nature, m\u00eame s'ils ne sont pas recycl\u00e9s.<\/strong><\/p>\n<p>Plus de la moiti\u00e9 des consommateurs dans le monde consid\u00e8rent l'emballage durable avant d'acheter un produit. Selon une analyse de Future Market Insights, la durabilit\u00e9 est le principal moteur de la croissance de l'emballage intelligent.<\/p>\n<p><a href=\"http:\/\/packagingstrategies.com\">packagingstrategies.com<\/a><\/p>\n<p>La perception selon laquelle les emballages en plastique sont plus n\u00e9fastes pour l'environnement que les autres incite de nombreuses marques d'emballage \u00e0 rechercher des alternatives. Qu'ils soient comestibles, biod\u00e9gradables, compostables ou simplement r\u00e9utilisables, les mat\u00e9riaux r\u00e9duisant les d\u00e9chets repr\u00e9sentent l'avenir des emballages pour aliments et boissons.<\/p>\n<p><a href=\"http:\/\/www.mintel.com\/blog\">www.mintel.com\/blog<\/a><\/p>\n<p>La France montre l'exemple et interdit depuis janvier 2022 les emballages plastiques pour la quasi-totalit\u00e9 des fruits et l\u00e9gumes afin de r\u00e9duire les d\u00e9chets plastiques. L'Espagne devrait suivre le mouvement \u00e0 partir de 2023.<\/p>\n<p><a href=\"http:\/\/www.thegrocer.co.uk\">www.thegrocer.co.uk<\/a><\/p>\n<p>Pour Winfried Muehling, directeur g\u00e9n\u00e9ral de Pro Carton, il s'agit d'une bonne nouvelle : \"Outre ses avantages in\u00e9gal\u00e9s pour l'environnement, le carton offre d'excellentes possibilit\u00e9s de prot\u00e9ger le produit dans le respect de l'environnement et de pr\u00e9senter les informations relatives au produit d'une mani\u00e8re conviviale pour le consommateur. L'emballage influence de plus en plus le caract\u00e8re de la marque, devenant une partie de plus en plus d\u00e9terminante de la marque. Avec les emballages en carton, nous sommes tr\u00e8s bien plac\u00e9s pour r\u00e9soudre les d\u00e9fis de nos clients.\"<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Sources<\/strong><\/p>\n<p><a href=\"http:\/\/absatzwirtschaft.de\">absatzwirtschaft.de<\/a><\/p>\n<p><a href=\"http:\/\/carbontrust.com\">carbontrust.com<\/a><\/p>\n<p><a href=\"http:\/\/drapersonline.com\">drapersonline.com<\/a><\/p>\n<p><a href=\"http:\/\/euromonitor.com\">euromonitor.com<\/a><\/p>\n<p><a href=\"http:\/\/heise.de\">heise.de<\/a><\/p>\n<p><a href=\"http:\/\/igd.com\">igd.com<\/a><\/p>\n<p><a href=\"http:\/\/jwtintelligence.com\">jwtintelligence.com<\/a><\/p>\n<p><a href=\"http:\/\/mintel.com\">mintel.com<\/a><\/p>\n<p><a href=\"http:\/\/packagingdigest.com\">packagingdigest.com<\/a><\/p>\n<p><a href=\"http:\/\/packagingstrategies.com\">packagingstrategies.com<\/a><\/p>\n<p><a href=\"http:\/\/packworld.com\">packworld.com<\/a><\/p>\n<p><a href=\"http:\/\/procarton.com\">procarton.com<\/a><\/p>\n<p><a href=\"http:\/\/trendbuero.com\">trendbuero.com<\/a><\/p>\n<p><a href=\"http:\/\/trendwatching.com\">trendwatching.com<\/a><\/p>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<div class=\"av-animated-generic top-to-bottom flex_column av_one_third  flex_column_div av-zero-column-padding   avia-builder-el-2  el_after_av_two_third  avia-builder-el-last\" style='border-radius:0px; '>\n<div  class='avia-image-container  av-styling-    avia-builder-el-3  avia-builder-el-no-sibling  avia-align-center'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  >\n<div class='avia-image-container-inner'>\n<div class='avia-image-overlay-wrap'><img decoding=\"async\" width=\"300\" height=\"160\" class='wp-image-275302 avia-img-lazy-loading-not-275302 avia_image' src=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio-300x160.jpg\" alt='' title='centre commercial virtuel alliancestudio'  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio-300x160.jpg 300w, https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio-1030x549.jpg 1030w, https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio-768x409.jpg 768w, https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio-1536x818.jpg 1536w, https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio-18x10.jpg 18w, https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio-1500x799.jpg 1500w, https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio-705x376.jpg 705w, https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio.jpg 1913w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Que disent les agences de tendances internationales \u00e0 propos de l'ann\u00e9e 2022 ? Pro Carton a compil\u00e9 les pr\u00e9visions les plus importantes pour le commerce de d\u00e9tail, les marques et les emballages.<\/p>","protected":false},"author":763,"featured_media":275302,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-275301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brands-markets"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2022 packaging trends - Pro Carton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.procarton.com\/fr\/2022-packaging-trends\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2022 packaging trends - Pro Carton\" \/>\n<meta property=\"og:description\" content=\"What do international trend agencies say about the year 2022? Pro Carton has compiled the most important forecasts for retail, brands and packaging.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.procarton.com\/fr\/2022-packaging-trends\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Carton\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/procartondesignaward\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-10T08:38:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-14T08:44:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1913\" \/>\n\t<meta property=\"og:image:height\" content=\"1019\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mediendesign\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:site\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mediendesign\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/\"},\"author\":{\"name\":\"Mediendesign\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/7c77a27683cd0ddceb1071c518193dc2\"},\"headline\":\"2022 packaging trends\",\"datePublished\":\"2022-03-10T08:38:50+00:00\",\"dateModified\":\"2022-03-14T08:44:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/\"},\"wordCount\":1643,\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/virtual-shopping-mall-alliancestudio.jpg\",\"articleSection\":[\"Brands &amp; Markets\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/\",\"name\":\"2022 packaging trends - Pro Carton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/virtual-shopping-mall-alliancestudio.jpg\",\"datePublished\":\"2022-03-10T08:38:50+00:00\",\"dateModified\":\"2022-03-14T08:44:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/virtual-shopping-mall-alliancestudio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/virtual-shopping-mall-alliancestudio.jpg\",\"width\":1913,\"height\":1019},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/2022-packaging-trends\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.procarton.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2022 packaging trends\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"name\":\"Pro Carton\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\",\"name\":\"ProCarton\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"width\":422,\"height\":519,\"caption\":\"ProCarton\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/procartondesignaward\\\/\",\"https:\\\/\\\/x.com\\\/pro_carton\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/7c77a27683cd0ddceb1071c518193dc2\",\"name\":\"Mediendesign\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/fr\\\/author\\\/mediendesign\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tendances en mati\u00e8re d'emballage pour 2022 - Pro Carton","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.procarton.com\/fr\/2022-packaging-trends\/","og_locale":"fr_FR","og_type":"article","og_title":"2022 packaging trends - Pro Carton","og_description":"What do international trend agencies say about the year 2022? Pro Carton has compiled the most important forecasts for retail, brands and packaging.","og_url":"https:\/\/www.procarton.com\/fr\/2022-packaging-trends\/","og_site_name":"Pro Carton","article_publisher":"https:\/\/www.facebook.com\/procartondesignaward\/","article_published_time":"2022-03-10T08:38:50+00:00","article_modified_time":"2022-03-14T08:44:55+00:00","og_image":[{"width":1913,"height":1019,"url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio.jpg","type":"image\/jpeg"}],"author":"Mediendesign","twitter_card":"summary_large_image","twitter_creator":"@pro_carton","twitter_site":"@pro_carton","twitter_misc":{"\u00c9crit par":"Mediendesign","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/#article","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/"},"author":{"name":"Mediendesign","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/7c77a27683cd0ddceb1071c518193dc2"},"headline":"2022 packaging trends","datePublished":"2022-03-10T08:38:50+00:00","dateModified":"2022-03-14T08:44:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/"},"wordCount":1643,"publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"image":{"@id":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio.jpg","articleSection":["Brands &amp; Markets"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/","url":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/","name":"Tendances en mati\u00e8re d'emballage pour 2022 - Pro Carton","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/#primaryimage"},"image":{"@id":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio.jpg","datePublished":"2022-03-10T08:38:50+00:00","dateModified":"2022-03-14T08:44:55+00:00","breadcrumb":{"@id":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.procarton.com\/es\/2022-packaging-trends\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/#primaryimage","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/03\/virtual-shopping-mall-alliancestudio.jpg","width":1913,"height":1019},{"@type":"BreadcrumbList","@id":"https:\/\/www.procarton.com\/es\/2022-packaging-trends\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.procarton.com\/"},{"@type":"ListItem","position":2,"name":"2022 packaging trends"}]},{"@type":"WebSite","@id":"https:\/\/www.procarton.com\/es\/#website","url":"https:\/\/www.procarton.com\/es\/","name":"Pro Carton","description":"","publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.procarton.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.procarton.com\/es\/#organization","name":"ProCarton","url":"https:\/\/www.procarton.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","width":422,"height":519,"caption":"ProCarton"},"image":{"@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/procartondesignaward\/","https:\/\/x.com\/pro_carton"]},{"@type":"Person","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/7c77a27683cd0ddceb1071c518193dc2","name":"Mediendesign","url":"https:\/\/www.procarton.com\/fr\/author\/mediendesign\/"}]}},"_links":{"self":[{"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/posts\/275301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/users\/763"}],"replies":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/comments?post=275301"}],"version-history":[{"count":5,"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/posts\/275301\/revisions"}],"predecessor-version":[{"id":276131,"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/posts\/275301\/revisions\/276131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/media\/275302"}],"wp:attachment":[{"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/media?parent=275301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/categories?post=275301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.procarton.com\/fr\/wp-json\/wp\/v2\/tags?post=275301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}