{"id":242121,"date":"2015-05-11T00:00:00","date_gmt":"2015-05-10T23:00:00","guid":{"rendered":"https:\/\/www.procarton.com\/pharma-in-motion\/"},"modified":"2021-11-07T16:01:14","modified_gmt":"2021-11-07T16:01:14","slug":"pharma-in-motion","status":"publish","type":"post","link":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/","title":{"rendered":"Farmacia en movimiento"},"content":{"rendered":"<p><strong>La demanda de atenci\u00f3n sanitaria es enorme y crece r\u00e1pidamente. Sin embargo, la industria farmac\u00e9utica se enfrenta a grandes retos. David Swift, antiguo responsable mundial de aprovisionamiento de envases en Novartis, habl\u00f3 con Pro Carton sobre la evoluci\u00f3n actual y futura.<\/strong><\/p>\n<p>El mercado farmac\u00e9utico est\u00e1 creciendo, pero sufrir\u00e1 cambios importantes en los pr\u00f3ximos a\u00f1os. Esto se debe a los elevados costes, la expiraci\u00f3n de las patentes, el creciente mercado de los productos gen\u00e9ricos, el considerable exceso de regulaci\u00f3n y las medidas de control del gasto p\u00fablico. \u00bfQu\u00e9 puede hacer la industria farmac\u00e9utica?<\/p>\n<p>\"Adem\u00e1s de las fusiones y adquisiciones, otros medios son la reducci\u00f3n de costes, el enfoque en los mercados emergentes, la transici\u00f3n del modelo de blockbuster a los productos de nicho y los cambios del modelo de distribuci\u00f3n farmac\u00e9utica. Algunas empresas tambi\u00e9n han deslocalizado cosas que no se hacen necesariamente en Europa\", dice David Swift.<\/p>\n<p>El crecimiento en Europa est\u00e1 impulsado por el envejecimiento de la poblaci\u00f3n. \"Los mercados de mayor crecimiento son China y Estados Unidos y, curiosamente, Alemania, seguidos de Brasil y Rusia. En los mercados desarrollados, el 71 % de los ingresos procede de los medicamentos especializados. Esto es importante, porque la forma de envasar y vender estos medicamentos es diferente. As\u00ed que el envasado tambi\u00e9n cambiar\u00e1\".<\/p>\n<p>El cambio m\u00e1s significativo en la distribuci\u00f3n es el modelo directo a la farmacia que est\u00e1n empleando ahora algunas de las empresas farmac\u00e9uticas. \"O bien prescinden por completo del mayorista, o bien prefieren un modelo en el que s\u00f3lo utilizan uno o dos mayoristas. As\u00ed, la relaci\u00f3n entre el productor de los medicamentos y los farmac\u00e9uticos es mucho m\u00e1s estrecha\".<\/p>\n<p>Diferentes medicamentos van a diferentes canales, hay una segmentaci\u00f3n. \"Algunos van a la farmacia directamente, otros a los pacientes directamente, otros a los hospitales, otros al mayorista - un mont\u00f3n de maneras diferentes. Los mayoristas tambi\u00e9n se est\u00e1n integrando verticalmente y suben y bajan en la cadena de valor\".<\/p>\n<p>&nbsp;<\/p>\n<h3>Implicaciones para el envasado farmac\u00e9utico<\/h3>\n<p>\"En lo que respecta a las l\u00edneas de producci\u00f3n, cada vez se presta m\u00e1s atenci\u00f3n a las \u00e1reas terap\u00e9uticas de \"alto valor\", como la oncolog\u00eda, la inmunolog\u00eda, los antivirales y el sistema nervioso central. En cuanto al tipo de medicamentos, crecer\u00e1n las jeringuillas precargadas, los autoinyectores y los dispositivos combinados. Los productos biol\u00f3gicos seguir\u00e1n superando el crecimiento del gasto farmac\u00e9utico global y se espera que representen entre 19 y 20 % del valor total del mercado en 2017\".<\/p>\n<p>En opini\u00f3n de Pro Carton, esto anuncia una serie de nuevos desarrollos en los envases:<\/p>\n<ol>\n<li>Los envases deben ser m\u00e1s atractivos para que los productos de marca sigan siendo comercializables tras la expiraci\u00f3n de las patentes. Deben transmitir el mensaje de la marca.<\/li>\n<li>El envasado debe crear est\u00edmulos de compra m\u00e1s fuertes, ya que los m\u00e9dicos y los pacientes desempe\u00f1ar\u00e1n un papel mucho m\u00e1s importante en la decisi\u00f3n de compra que hasta ahora, y la influencia de los mayoristas est\u00e1 disminuyendo.<\/li>\n<li>Esto se aplica a\u00fan m\u00e1s a los productos que tienen que mantenerse en un mercado sanitario m\u00e1s amplio: su envase debe reforzar la fidelidad del cliente en todos los aspectos y estimular la recompra del producto.<\/li>\n<li>Los envases reflejar\u00e1n los productos de alto valor y el valor de los nuevos productos especiales, cuya importancia aumentar\u00e1 sobre todo en Europa.<\/li>\n<li>El envasado ser\u00e1 mucho m\u00e1s complejo debido a los productos biol\u00f3gicos y las jeringuillas, as\u00ed como a las terapias con diferentes medicamentos.<\/li>\n<li>Esto hace que los fabricantes de envases deban dar un gran valor a la comodidad cuando los envases complejos van al encuentro de una poblaci\u00f3n envejecida en Europa.<\/li>\n<li>Los envases ser\u00e1n sin duda m\u00e1s inteligentes en t\u00e9rminos de informaci\u00f3n y enlaces a Internet: esto proporcionar\u00e1 amplia informaci\u00f3n adicional sobre su modo de acci\u00f3n y eficacia.<\/li>\n<\/ol>\n<p>El mercado de los envases farmac\u00e9uticos ya se ha distinguido por sus exigentes soluciones. El desarrollo din\u00e1mico del mercado ofrece ahora a todos los socios de la cadena de suministro la oportunidad mutua de desarrollar nuevos conceptos creativos.<\/p>","protected":false},"excerpt":{"rendered":"<p>La demanda de atenci\u00f3n sanitaria es enorme y crece r\u00e1pidamente. No obstante, la industria farmac\u00e9utica se enfrenta a grandes retos.<\/p>","protected":false},"author":1,"featured_media":242122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[79],"tags":[45],"class_list":["post-242121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brands-markets","tag-experts-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pharma in motion - Pro Carton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.procarton.com\/es\/pharma-in-motion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pharma in motion - Pro Carton\" \/>\n<meta property=\"og:description\" content=\"There is a huge demand for health care, and it\u2019s growing rapidly. Nonetheless, the pharmaceutical industry is facing major challenges.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.procarton.com\/es\/pharma-in-motion\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Carton\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/procartondesignaward\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-10T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-07T16:01:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/049-3_cut.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"esterling@admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:site\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"esterling@admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/\"},\"author\":{\"name\":\"esterling@admin\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\"},\"headline\":\"Pharma in motion\",\"datePublished\":\"2015-05-10T23:00:00+00:00\",\"dateModified\":\"2021-11-07T16:01:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/\"},\"wordCount\":583,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/049-3_cut.jpg\",\"keywords\":[\"Experts\"],\"articleSection\":[\"Brands &amp; Markets\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/\",\"name\":\"Pharma in motion - Pro Carton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/049-3_cut.jpg\",\"datePublished\":\"2015-05-10T23:00:00+00:00\",\"dateModified\":\"2021-11-07T16:01:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/049-3_cut.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/049-3_cut.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/pharma-in-motion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.procarton.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pharma in motion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"name\":\"Pro Carton\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\",\"name\":\"ProCarton\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"width\":422,\"height\":519,\"caption\":\"ProCarton\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/procartondesignaward\\\/\",\"https:\\\/\\\/x.com\\\/pro_carton\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\",\"name\":\"esterling@admin\",\"sameAs\":[\"https:\\\/\\\/www.procarton.com\"],\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/author\\\/esterlingadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Farmacia en movimiento - Pro Carton","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/","og_locale":"es_ES","og_type":"article","og_title":"Pharma in motion - Pro Carton","og_description":"There is a huge demand for health care, and it\u2019s growing rapidly. Nonetheless, the pharmaceutical industry is facing major challenges.","og_url":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/","og_site_name":"Pro Carton","article_publisher":"https:\/\/www.facebook.com\/procartondesignaward\/","article_published_time":"2015-05-10T23:00:00+00:00","article_modified_time":"2021-11-07T16:01:14+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/049-3_cut.jpg","type":"image\/jpeg"}],"author":"esterling@admin","twitter_card":"summary_large_image","twitter_creator":"@pro_carton","twitter_site":"@pro_carton","twitter_misc":{"Escrito por":"esterling@admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/#article","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/"},"author":{"name":"esterling@admin","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251"},"headline":"Pharma in motion","datePublished":"2015-05-10T23:00:00+00:00","dateModified":"2021-11-07T16:01:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/"},"wordCount":583,"commentCount":0,"publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"image":{"@id":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/049-3_cut.jpg","keywords":["Experts"],"articleSection":["Brands &amp; Markets"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.procarton.com\/es\/pharma-in-motion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/","url":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/","name":"Farmacia en movimiento - Pro Carton","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/#primaryimage"},"image":{"@id":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/049-3_cut.jpg","datePublished":"2015-05-10T23:00:00+00:00","dateModified":"2021-11-07T16:01:14+00:00","breadcrumb":{"@id":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.procarton.com\/es\/pharma-in-motion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/#primaryimage","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/049-3_cut.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/049-3_cut.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.procarton.com\/es\/pharma-in-motion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.procarton.com\/"},{"@type":"ListItem","position":2,"name":"Pharma in motion"}]},{"@type":"WebSite","@id":"https:\/\/www.procarton.com\/es\/#website","url":"https:\/\/www.procarton.com\/es\/","name":"Pro Carton","description":"","publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.procarton.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.procarton.com\/es\/#organization","name":"ProCarton","url":"https:\/\/www.procarton.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","width":422,"height":519,"caption":"ProCarton"},"image":{"@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/procartondesignaward\/","https:\/\/x.com\/pro_carton"]},{"@type":"Person","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251","name":"esterling@admin","sameAs":["https:\/\/www.procarton.com"],"url":"https:\/\/www.procarton.com\/es\/author\/esterlingadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/posts\/242121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/comments?post=242121"}],"version-history":[{"count":1,"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/posts\/242121\/revisions"}],"predecessor-version":[{"id":266160,"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/posts\/242121\/revisions\/266160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/media\/242122"}],"wp:attachment":[{"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/media?parent=242121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/categories?post=242121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.procarton.com\/es\/wp-json\/wp\/v2\/tags?post=242121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}