{"id":243553,"date":"2020-12-16T00:00:00","date_gmt":"2020-12-16T00:00:00","guid":{"rendered":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/"},"modified":"2021-11-05T17:40:19","modified_gmt":"2021-11-05T17:40:19","slug":"its-not-all-doom-and-gloom","status":"publish","type":"post","link":"https:\/\/www.procarton.com\/de\/its-not-all-doom-and-gloom\/","title":{"rendered":"Es ist nicht alles d\u00fcster!"},"content":{"rendered":"<p><strong>Die meisten von uns sprechen \u00fcber die H\u00e4rten, die Covid-19 mit sich gebracht hat, aber es gibt auch viel Positives, wie wir im Vereinigten K\u00f6nigreich sagen: \"Jede Wolke hat einen Silberstreif\". Insbesondere in der Kartonindustrie haben wir Grund zu der Zuversicht, dass wir insgesamt gest\u00e4rkt und mit neuen und besseren Arbeitsmethoden aus der Pandemie hervorgehen werden.<\/strong><\/p>\n<p>Werfen wir also einen Blick auf einige der Vorteile, die sich in den letzten neun Monaten ergeben haben, einige davon ernsthaft, andere etwas heiterer (es ist ja fast Weihnachten!).<\/p>\n<p><strong>1) Mehr Bewusstsein f\u00fcr die Umwelt<\/strong><br \/>\nEs bestand die Sorge, dass die kurzfristigen praktischen Erw\u00e4gungen, die durch die Pandemie hervorgerufen wurden, die Oberhand \u00fcber die l\u00e4ngerfristige Notwendigkeit eines umweltfreundlicheren Verhaltens gewinnen w\u00fcrden. Sicherlich gab es einige unerw\u00fcnschte, aber unvermeidbare Zunahmen bei nicht wiederverwertbarer Schutzkleidung, aber insgesamt hat die Pandemie dazu gef\u00fchrt, dass wir uns eher mehr als weniger Sorgen um die Umwelt machen. Eine im November 2020 von Pro Carton durchgef\u00fchrte Umfrage unter 10 500 Europ\u00e4ern ergab, dass der Klimawandel die gr\u00f6\u00dfte Sorge der Verbraucher nach Covid-19 war, und dass nur 21% der Befragten angaben, dass sie sich weniger Sorgen um die Umwelt machten als vor Covid-19, wobei die H\u00e4lfte sagte, dass sie sich MEHR Sorgen machten. Offensichtlich steht die Umwelt weiterhin ganz oben auf der Agenda der Menschen, und das kann f\u00fcr Karton und Pappe nur gut sein.<\/p>\n<p><a href=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2020\/12\/doom2.jpg\"><img decoding=\"async\" class=\"alignnone wp-image-107395\" style=\"width: 600px!important;\" src=\" https:\/\/www.procarton.com\/wp-content\/uploads\/2020\/12\/doom2-600.jpg\" alt=\"Umgebungsgrafik\" width=\"600\" \/><\/a><\/p>\n<p><strong>2) Die Verpackung ist wichtig<\/strong><br \/>\nDie Europ\u00e4ische Kommission und die \u00d6ffentlichkeit im Allgemeinen haben erkannt, dass Verpackungen und die Besch\u00e4ftigten in der Branche unverzichtbar sind. Die Verpackung hat in den letzten Jahren zu Unrecht eine schlechte Presse bekommen, und es ist ermutigend zu sehen, dass so viele Marken auf Verpackungen umsteigen, die erneuerbar, recycelbar und biologisch abbaubar sind - wie zum Beispiel Karton.<\/p>\n<p><strong>3) Verbindet alle Generationen<\/strong><br \/>\nDie Technologie wird von jungen Menschen nat\u00fcrlicher und schneller angenommen. Aber inzwischen sind Menschen aller Altersgruppen besser mit Computern und Technologien vertraut und nehmen gerne an Online-Videokonferenzen teil, sei es mit Zoom, Microsoft Teams, Go to Meeting, Skype, Webex oder sogar House Party! 60 ist schlie\u00dflich das neue 40.<\/p>\n<p><strong>4) Mehr Effizienz<\/strong><br \/>\nW\u00e4hrend pers\u00f6nliche Besprechungen ein Comeback erleben werden (hoffe ich!), sind Videokonferenzen auf dem Vormarsch. Die wichtigsten Vorteile sind Zeit und Geld; weniger Reisen und unn\u00f6tige Kosten - was kann sich ein Finanzdirektor mehr w\u00fcnschen (es sei denn, er arbeitet in der Luftfahrtbranche)?<\/p>\n<p><strong>5) Mehr Zusammenarbeit<\/strong><br \/>\nWir sitzen alle im selben Boot. Nie zuvor gab es ein so globales kollektives Handeln und auch ein Gef\u00fchl der Anerkennung f\u00fcr diejenigen, die anderen helfen. Vielleicht haben wir ein wenig Mitgef\u00fchl und Widerstandskraft zur\u00fcckgewonnen, auch wenn der Egoismus immer noch deutlich zu sp\u00fcren war, als die Panikk\u00e4ufer die Regale in unseren Superm\u00e4rkten mit Toilettenpapier und anderen lebenswichtigen Dingen leerr\u00e4umten.<\/p>\n<p><strong>6) Wir m\u00fcssen f\u00fcr uns selbst sorgen<\/strong><br \/>\nDa Arztbesuche immer schwieriger zu arrangieren sind und niemand ins Krankenhaus gehen m\u00f6chte, mussten wir uns selbst diagnostizieren und haben vielleicht erkannt, dass unsere Gesundheit in unserer eigenen Verantwortung liegt. Immer mehr Menschen bewegen sich an der frischen Luft, um sich zu bewegen und um sich von der h\u00e4uslichen Umgebung zu erholen. Der Verkauf von Spinning-Bikes und Hantelscheiben ist ebenfalls in die H\u00f6he geschnellt.<\/p>\n<p><strong>7) Mehr Hausmannskost<\/strong><br \/>\nDa die Restaurants geschlossen sind, kochen immer mehr Menschen zu Hause. Und zwar nicht nur, um ein tiefgek\u00fchltes Mikrowellengericht aufzuw\u00e4rmen, sondern um ges\u00fcndere und qualitativ bessere Mahlzeiten zuzubereiten. Zwei der Artikel, die zu Beginn der Schlie\u00dfung in den Gesch\u00e4ften ausverkauft waren, waren Mehl und Hefe, was darauf schlie\u00dfen l\u00e4sst, dass die Zahl der Selbstgebackenen enorm gestiegen ist. Viele haben festgestellt, dass ihnen das Kochen Spa\u00df macht, obwohl das Beste die Anerkennung durch die Familie ist, wenn etwas gut gelungen ist. Denken Sie daran, dass wir alle gerne gelobt werden.<\/p>\n<p><strong>8) Verbesserte Hygiene<\/strong><br \/>\nEs wurde immer wieder betont, wie wichtig es ist, sich die H\u00e4nde richtig zu waschen (mit Seife!) und Desinfektionsmittel zu benutzen, und die Zahl derer, die dies tun, ist erheblich gestiegen.<br \/>\nEs gibt jedoch immer noch zu viele Maskentr\u00e4ger, die zu glauben scheinen, dass das Abdecken des Mundes (aber nicht der Nase) oder sogar nur des Kinns einen ausreichenden Schutz f\u00fcr sie selbst und andere in ihrer Umgebung darstellt.<\/p>\n<p><strong>9) Geringere Verschmutzung<\/strong><br \/>\nDa weniger Flugverkehr und auch weniger Autofahrten stattfinden, ist die Luft viel sauberer als in vielen anderen Jahren. Haben Sie bemerkt, dass die Luft anders riecht und Sie die V\u00f6gel viel deutlicher h\u00f6ren k\u00f6nnen? Hoffen wir, dass dies nicht nur ein vor\u00fcbergehender Vorteil ist. Das Aufkommen von Videokonferenzen und die Zunahme von Elektroautos werden sicherlich dazu beitragen.<\/p>\n<p><strong>10) Der Weihnachtsmann ist befreit<\/strong><br \/>\nEine gute Nachricht f\u00fcr Kinder jeden Alters ist, dass best\u00e4tigt wurde, dass der Weihnachtsmann von den Quarant\u00e4ne- und Reisebeschr\u00e4nkungen ausgenommen ist, da er ein wichtiger Arbeitnehmer ist.<br \/>\nDer irische Au\u00dfenminister, <a href=\"https:\/\/www.youtube.com\/watch?v=zRXgGPGk9Ow\">Simon Coveney<\/a>best\u00e4tigte am 26. November im Parlament, dass:<br \/>\n\"Wir betrachten die Reise des Weihnachtsmanns als unerl\u00e4ssliche Reise\", was bedeutet, dass der Weihnachtsmann von der Pflicht zur Selbstquarant\u00e4ne befreit ist. \"Der Weihnachtsmann wird in der Lage sein, in unseren Luftraum und sogar in unsere H\u00e4user zu kommen\", sagte der Minister, \"ohne dass wir seine Bewegungsfreiheit einschr\u00e4nken m\u00fcssen\".<\/p>\n<p>Coveney forderte jedoch, dass die Kinder im Bett bleiben sollten, um die soziale Distanz zu wahren, wenn der Weihnachtsmann ihre Geschenke ausliefert. Auch die Rentiere des Weihnachtsmanns sind fit und gesund, denn sie haben eine Herdenimmunit\u00e4t!<\/p>\n<p><strong>Ich w\u00fcnsche Ihnen ein sch\u00f6nes Weihnachtsfest und ein erfolgreiches neues Jahr.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Die meisten von uns sprechen \u00fcber die H\u00e4rten, die Covid-19 mit sich gebracht hat, aber es gibt auch viel Positives, wie wir im Vereinigten K\u00f6nigreich sagen: \"Jede Wolke hat einen Silberstreif\". Insbesondere in der Kartonindustrie haben wir Grund zu der Zuversicht, dass wir insgesamt gest\u00e4rkt und mit neuen und besseren Arbeitsmethoden aus der Pandemie hervorgehen werden.<\/p>","protected":false},"author":1,"featured_media":243554,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[45],"class_list":["post-243553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-other","tag-experts-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>It\u2019s not all doom and gloom! - Pro Carton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.procarton.com\/de\/its-not-all-doom-and-gloom\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"It\u2019s not all doom and gloom! - Pro Carton\" \/>\n<meta property=\"og:description\" content=\"Most of us talk about the hardships that Covid-19 has brought but there have many positives, as we say in the UK \u201cevery cloud has a silver lining\u201d. In the carton industry in particular, I think we have reason to be confident that overall we will come out of the pandemic stronger and with new and better ways of working.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.procarton.com\/de\/its-not-all-doom-and-gloom\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Carton\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/procartondesignaward\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-16T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-05T17:40:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/doom-600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"esterling@admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:site\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"esterling@admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/\"},\"author\":{\"name\":\"esterling@admin\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\"},\"headline\":\"It\u2019s not all doom and gloom!\",\"datePublished\":\"2020-12-16T00:00:00+00:00\",\"dateModified\":\"2021-11-05T17:40:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/\"},\"wordCount\":839,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/doom-600.jpg\",\"keywords\":[\"Experts\"],\"articleSection\":[\"Other\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/\",\"name\":\"It\u2019s not all doom and gloom! - Pro Carton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/doom-600.jpg\",\"datePublished\":\"2020-12-16T00:00:00+00:00\",\"dateModified\":\"2021-11-05T17:40:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/doom-600.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/doom-600.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/its-not-all-doom-and-gloom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.procarton.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"It\u2019s not all doom and gloom!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"name\":\"Pro Carton\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\",\"name\":\"ProCarton\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"width\":422,\"height\":519,\"caption\":\"ProCarton\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/procartondesignaward\\\/\",\"https:\\\/\\\/x.com\\\/pro_carton\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\",\"name\":\"esterling@admin\",\"sameAs\":[\"https:\\\/\\\/www.procarton.com\"],\"url\":\"https:\\\/\\\/www.procarton.com\\\/de\\\/author\\\/esterlingadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Es ist nicht alles d\u00fcster! - Pro Karton","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.procarton.com\/de\/its-not-all-doom-and-gloom\/","og_locale":"de_DE","og_type":"article","og_title":"It\u2019s not all doom and gloom! - Pro Carton","og_description":"Most of us talk about the hardships that Covid-19 has brought but there have many positives, as we say in the UK \u201cevery cloud has a silver lining\u201d. In the carton industry in particular, I think we have reason to be confident that overall we will come out of the pandemic stronger and with new and better ways of working.","og_url":"https:\/\/www.procarton.com\/de\/its-not-all-doom-and-gloom\/","og_site_name":"Pro Carton","article_publisher":"https:\/\/www.facebook.com\/procartondesignaward\/","article_published_time":"2020-12-16T00:00:00+00:00","article_modified_time":"2021-11-05T17:40:19+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/doom-600.jpg","type":"image\/jpeg"}],"author":"esterling@admin","twitter_card":"summary_large_image","twitter_creator":"@pro_carton","twitter_site":"@pro_carton","twitter_misc":{"Verfasst von":"esterling@admin","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/#article","isPartOf":{"@id":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/"},"author":{"name":"esterling@admin","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251"},"headline":"It\u2019s not all doom and gloom!","datePublished":"2020-12-16T00:00:00+00:00","dateModified":"2021-11-05T17:40:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/"},"wordCount":839,"commentCount":0,"publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"image":{"@id":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/doom-600.jpg","keywords":["Experts"],"articleSection":["Other"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/","url":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/","name":"Es ist nicht alles d\u00fcster! - Pro Karton","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/#primaryimage"},"image":{"@id":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/doom-600.jpg","datePublished":"2020-12-16T00:00:00+00:00","dateModified":"2021-11-05T17:40:19+00:00","breadcrumb":{"@id":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/#primaryimage","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/doom-600.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/doom-600.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.procarton.com\/its-not-all-doom-and-gloom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.procarton.com\/"},{"@type":"ListItem","position":2,"name":"It\u2019s not all doom and gloom!"}]},{"@type":"WebSite","@id":"https:\/\/www.procarton.com\/es\/#website","url":"https:\/\/www.procarton.com\/es\/","name":"Pro Carton","description":"","publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.procarton.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.procarton.com\/es\/#organization","name":"ProCarton","url":"https:\/\/www.procarton.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","width":422,"height":519,"caption":"ProCarton"},"image":{"@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/procartondesignaward\/","https:\/\/x.com\/pro_carton"]},{"@type":"Person","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251","name":"esterling@admin","sameAs":["https:\/\/www.procarton.com"],"url":"https:\/\/www.procarton.com\/de\/author\/esterlingadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts\/243553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/comments?post=243553"}],"version-history":[{"count":2,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts\/243553\/revisions"}],"predecessor-version":[{"id":265753,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts\/243553\/revisions\/265753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/media\/243554"}],"wp:attachment":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/media?parent=243553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/categories?post=243553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/tags?post=243553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}