{"id":242406,"date":"2018-12-04T00:00:00","date_gmt":"2018-12-04T00:00:00","guid":{"rendered":"https:\/\/www.procarton.com\/so-what-do-shoppers-really-think\/"},"modified":"2021-11-05T18:09:11","modified_gmt":"2021-11-05T18:09:11","slug":"so-what-do-shoppers-really-think","status":"publish","type":"post","link":"https:\/\/www.procarton.com\/de\/so-what-do-shoppers-really-think\/","title":{"rendered":"Was denken die K\u00e4ufer also wirklich?"},"content":{"rendered":"<p><strong>Die Ergebnisse von Pro Carton's <a href=\"https:\/\/www.procarton.com\/publications-news\/publications\/?publication_type=studies\">Europ\u00e4ische Studie \u00fcber die Wahrnehmung von Verpackungen durch Verbraucher<\/a> wurden erstmals in der j\u00fcngsten Ausgabe der <a href=\"https:\/\/www.procarton.com\/publications-news\/publications\/?publication_type=pro-carton-magazine\">Zeitschrift Pro Carton<\/a> und auf dem ECMA-Kongress im September. Der gedruckte Forschungsbericht wurde nun ver\u00f6ffentlicht und steht auch auf unserer Website zum Download bereit. Die Untersuchung hat deutlich gezeigt, welche enorme Bedeutung die Verbraucher umweltfreundlichen Verpackungen beimessen und wie gro\u00df die Bereitschaft zu Ver\u00e4nderungen ist. Der Bericht enth\u00e4lt zwar die wichtigsten Ergebnisse der Studie, aber ich m\u00f6chte auch einige der Statistiken vorstellen, die es nicht in die endg\u00fcltige Fassung geschafft haben.<\/strong><\/p>\n<p>F\u00fcr diejenigen, die mit der Studie nicht vertraut sind: Sie wurde von Coleman Parkes Research im Sommer unter 7.000 Befragten durchgef\u00fchrt, die sich zu gleichen Teilen auf sieben L\u00e4nder - Frankreich, Deutschland, Italien, Polen, Spanien, T\u00fcrkei und das Vereinigte K\u00f6nigreich - verteilen.<\/p>\n<p>Das erste, was mir auffiel, war, wie \u00e4hnlich die Ergebnisse in den einzelnen L\u00e4ndern insgesamt waren. Das Umweltthema hat eindeutig die Aufmerksamkeit der Verbraucher in ganz Europa erregt, wobei die Ergebnisse im \u00f6stlichen Teil Europas weitgehend mit denen im Westen \u00fcbereinstimmen. Die Welt wird wohl oder \u00fcbel immer mehr zu einem homogenen Ort.<\/p>\n<p>Eines der auff\u00e4lligsten Ergebnisse war die gro\u00dfe Zahl der Menschen, die bereit sind, mehr f\u00fcr Produkte in umweltfreundlicheren Verpackungen zu bezahlen. Fast 4 von 5 Verbrauchern gaben an, dass sie bereit w\u00e4ren, mehr zu zahlen, wenn die Verpackung die Umwelt nicht sch\u00e4digt, wobei Polen das Land ist, das am meisten bereit ist, mehr zu zahlen. Nat\u00fcrlich gibt es einen Unterschied zwischen Verhalten und Einstellung, aber diese Zahl hat mich \u00fcberrascht und zeigt deutlich, wie stark die Gef\u00fchle sind.<a href=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/grafik-1-EN-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-200639\" src=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/grafik-1-EN-1-scaled.jpg\" alt=\"\" width=\"4300\" height=\"3700\" \/><\/a><\/p>\n<p><em><strong>Wie viel mehr w\u00fcrden Sie f\u00fcr ein Produkt bezahlen, wenn die Verpackung Ihres Wunschprodukts die Umwelt weniger belasten w\u00fcrde? 77% w\u00fcrde mehr bezahlen!<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Die Verbraucher sind auch besorgt \u00fcber das Tempo des Wandels oder vielmehr \u00fcber das Fehlen eines solchen. 64% finden, dass Einzelh\u00e4ndler und Marken nicht genug tun, um umweltfreundliche Verpackungen einzuf\u00fchren, wobei die Verbraucher im Vereinigten K\u00f6nigreich am kritischsten sind.<a href=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/grafik-2-EN-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-200575\" src=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/grafik-2-EN-scaled.jpg\" alt=\"\" width=\"3000\" height=\"3200\" \/><\/a><\/p>\n<p><em><strong>Tun Einzelh\u00e4ndler und Marken Ihrer Meinung nach genug, um umweltfreundliche Verpackungsformen einzuf\u00fchren?<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Was mich \u00fcberraschte, war, dass Dosen als das am wenigsten recycelbare und umweltfreundliche Material angesehen wurden, noch hinter Kunststoff. Es ist klar, dass Metal Packaging Europe (der Handelsverband der Getr\u00e4nkedosen- und Metallverpackungsindustrie) eine gro\u00dfe Aufgabe zu erledigen hat. Erfreulicherweise wurde Karton mit einigem Abstand als das umweltfreundlichste Material angesehen.<a href=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/grafik-3-EN-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-200607\" src=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/grafik-3-EN-scaled.jpg\" alt=\"\" width=\"2800\" height=\"2600\" \/><\/a><\/p>\n<p><em><strong>Welches ist die am besten wiederverwertbare Verpackungsart? Karton, nat\u00fcrlich.<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Nun zu einigen Dingen, die nicht in dem Bericht stehen, aber dennoch interessant sind, insbesondere f\u00fcr diejenigen, die in der Karton-\/Kartonindustrie arbeiten.<\/p>\n<p>W\u00e4hrend 71% der Befragten angaben, \u00fcber die Umweltauswirkungen von Kunststoffverpackungen besorgt zu sein, hatten 41% \u00e4hnliche Bedenken in Bezug auf Kartons\/Karton. Dies scheint haupts\u00e4chlich auf die falsche Vorstellung von der Abholzung der W\u00e4lder in Europa zur\u00fcckzuf\u00fchren zu sein. Die Leser werden wissen, dass die europ\u00e4ischen W\u00e4lder in den letzten Jahren mit einer Geschwindigkeit gewachsen sind, die 1.500 Fu\u00dfballfeldern pro Tag entspricht, aber die Botschaft muss noch verst\u00e4rkt werden. Den Untersuchungen zufolge wissen die meisten Verbraucher jedoch, dass Karton biologisch abbaubar ist und recyceltes Material gut verwendet werden kann.<\/p>\n<p>Eine Frage, bei der es deutliche Meinungsunterschiede zwischen den einzelnen L\u00e4ndern gab, war die Frage, ob eine Steuer eingef\u00fchrt werden sollte, um Marken und Einzelh\u00e4ndler zu zwingen, umweltfreundlichere Verpackungsformen zu verwenden. In Italien stimmten 74% der Bev\u00f6lkerung dieser Aussage zu, 49% stimmten voll und ganz zu - fast doppelt so viele wie in den anderen L\u00e4ndern. Es ist wahrscheinlich kein Zufall, dass italienische Regierungsminister im Oktober dieses Jahres ein neues gr\u00fcnes Wirtschaftsmodell forderten, das nicht auf Gewinnmaximierung ausgerichtet ist.<\/p>\n<p>Der italienische Umweltminister Sergio Costa sagte, dass die Regierung mit der \u00dcbertragung der Zust\u00e4ndigkeit f\u00fcr die Kreislaufwirtschaft an sein Ministerium zeige, dass sie \"wirklich verstanden hat, dass die Zukunft des Planeten nicht auf der Maximierung des Profits basieren kann\".<\/p>\n<p>Er f\u00fcgte hinzu: \"Diejenigen, die f\u00fcr die Wirtschaft verantwortlich sind, m\u00fcssen an ein Prinzip denken, nicht an die Steigerung des Gewinns als Hauptbezugspunkt, sondern an den richtigen Verdienst, den richtigen Gewinn. Das ist ein gro\u00dfer, gro\u00dfer Unterschied.\" Eine ganz andere Herangehensweise an den Handel und die Wirtschaft, die den italienischen Verbrauchern entgegenzukommen scheint.<\/p>\n<p>Es \u00fcberrascht nicht, dass das Alter der Befragten einige Unterschiede in der Einstellung zeigte. Am besorgniserregendsten war vielleicht die Frage der Abholzung, wobei die \u00e4lteren Verbraucher weitaus besser informiert waren als die j\u00fcngeren. W\u00e4hrend weniger als ein Drittel der \u00fcber 60-J\u00e4hrigen der Meinung war, dass Karton Abholzung verursacht, waren 47% der 19-29-J\u00e4hrigen dieser Meinung. Es liegt auf der Hand, dass die Branche mit jungen Verbrauchern kommunizieren muss, weshalb Aktivit\u00e4ten wie das neue Schulbildungsprogramm von Pro Carton (<a href=\"https:\/\/www.procarton.com\/sustainability\/ticcit\/\">TICCIT - B\u00e4ume zu Kartons, Kartons zu B\u00e4umen<\/a>), die <a href=\"https:\/\/www.procarton.com\/awards\/pro-carton-young-designers-award\/2019\/\">Pro Carton Young Designers Award<\/a> und unsere wachsende Pr\u00e4senz auf Facebook, LinkedIn und Co. noch relevanter und wichtiger. Ihre Unterst\u00fctzung f\u00fcr diese und andere Aktivit\u00e4ten ist entscheidend. Bitte ermutigen Sie Ihre Familie und Kollegen, uns in den sozialen Medien zu \"folgen\", zu \"teilen\" und zu \"m\u00f6gen\" und helfen Sie mit, die Botschaft von Karton - erneuerbar, recycelbar, biologisch abbaubar, wirklich nachhaltig - an die j\u00fcngere Generation weiterzugeben.<\/p>\n<p>Wenn ich Ihren Appetit geweckt habe, k\u00f6nnen Sie mehr lesen unter <a href=\"https:\/\/www.procarton.com\/publications-news\/publications\/?publication_type=studies\">der Bericht<\/a>. Es ist in mehreren Sprachen verf\u00fcgbar, zusammen mit dem <a href=\"https:\/\/www.procarton.com\/publications-news\/publications\/\">Infografiken<\/a> die in Ihren Pr\u00e4sentationen verwendet werden k\u00f6nnen.<\/p>\n<p><em>Tony Hitchin, Generaldirektor Pro Carton<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>The results of Pro Carton\u2019s European Consumer Packaging Perceptions study were first previewed in the latest edition of the Pro Carton magazine and at the ECMA Congress back in September. The printed research report now has been published and is also available for download from our website. The research clearly showed the enormous importance that [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":242410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[79,52],"tags":[45],"class_list":["post-242406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brands-markets","category-sustainability","tag-experts-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>So what do shoppers really think? - Pro Carton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.procarton.com\/de\/so-what-do-shoppers-really-think\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"So what do shoppers really think? - Pro Carton\" \/>\n<meta property=\"og:description\" content=\"The results of Pro Carton\u2019s European Consumer Packaging Perceptions study were first previewed in the latest edition of the Pro Carton magazine and at the ECMA Congress back in September. The printed research report now has been published and is also available for download from our website. The research clearly showed the enormous importance that [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.procarton.com\/de\/so-what-do-shoppers-really-think\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Carton\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/procartondesignaward\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-04T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-05T18:09:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/study-cover-EN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"esterling@admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:site\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"esterling@admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/\"},\"author\":{\"name\":\"esterling@admin\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\"},\"headline\":\"So what do shoppers really think?\",\"datePublished\":\"2018-12-04T00:00:00+00:00\",\"dateModified\":\"2021-11-05T18:09:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/\"},\"wordCount\":882,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/study-cover-EN.jpg\",\"keywords\":[\"Experts\"],\"articleSection\":[\"Brands &amp; Markets\",\"Sustainability\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/\",\"name\":\"So what do shoppers really think? - Pro Carton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/study-cover-EN.jpg\",\"datePublished\":\"2018-12-04T00:00:00+00:00\",\"dateModified\":\"2021-11-05T18:09:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/study-cover-EN.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/study-cover-EN.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/so-what-do-shoppers-really-think\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.procarton.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"So what do shoppers really think?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"name\":\"Pro Carton\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\",\"name\":\"ProCarton\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"width\":422,\"height\":519,\"caption\":\"ProCarton\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/procartondesignaward\\\/\",\"https:\\\/\\\/x.com\\\/pro_carton\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\",\"name\":\"esterling@admin\",\"sameAs\":[\"https:\\\/\\\/www.procarton.com\"],\"url\":\"https:\\\/\\\/www.procarton.com\\\/de\\\/author\\\/esterlingadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Und was denken die K\u00e4ufer wirklich? - Pro Karton","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.procarton.com\/de\/so-what-do-shoppers-really-think\/","og_locale":"de_DE","og_type":"article","og_title":"So what do shoppers really think? - Pro Carton","og_description":"The results of Pro Carton\u2019s European Consumer Packaging Perceptions study were first previewed in the latest edition of the Pro Carton magazine and at the ECMA Congress back in September. The printed research report now has been published and is also available for download from our website. The research clearly showed the enormous importance that [&hellip;]","og_url":"https:\/\/www.procarton.com\/de\/so-what-do-shoppers-really-think\/","og_site_name":"Pro Carton","article_publisher":"https:\/\/www.facebook.com\/procartondesignaward\/","article_published_time":"2018-12-04T00:00:00+00:00","article_modified_time":"2021-11-05T18:09:11+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/study-cover-EN.jpg","type":"image\/jpeg"}],"author":"esterling@admin","twitter_card":"summary_large_image","twitter_creator":"@pro_carton","twitter_site":"@pro_carton","twitter_misc":{"Verfasst von":"esterling@admin","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/#article","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/"},"author":{"name":"esterling@admin","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251"},"headline":"So what do shoppers really think?","datePublished":"2018-12-04T00:00:00+00:00","dateModified":"2021-11-05T18:09:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/"},"wordCount":882,"commentCount":0,"publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"image":{"@id":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/study-cover-EN.jpg","keywords":["Experts"],"articleSection":["Brands &amp; Markets","Sustainability"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/","url":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/","name":"Und was denken die K\u00e4ufer wirklich? - Pro Karton","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/#primaryimage"},"image":{"@id":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/study-cover-EN.jpg","datePublished":"2018-12-04T00:00:00+00:00","dateModified":"2021-11-05T18:09:11+00:00","breadcrumb":{"@id":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/#primaryimage","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/study-cover-EN.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/study-cover-EN.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.procarton.com\/es\/so-what-do-shoppers-really-think\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.procarton.com\/"},{"@type":"ListItem","position":2,"name":"So what do shoppers really think?"}]},{"@type":"WebSite","@id":"https:\/\/www.procarton.com\/es\/#website","url":"https:\/\/www.procarton.com\/es\/","name":"Pro Carton","description":"","publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.procarton.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.procarton.com\/es\/#organization","name":"ProCarton","url":"https:\/\/www.procarton.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","width":422,"height":519,"caption":"ProCarton"},"image":{"@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/procartondesignaward\/","https:\/\/x.com\/pro_carton"]},{"@type":"Person","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251","name":"esterling@admin","sameAs":["https:\/\/www.procarton.com"],"url":"https:\/\/www.procarton.com\/de\/author\/esterlingadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts\/242406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/comments?post=242406"}],"version-history":[{"count":1,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts\/242406\/revisions"}],"predecessor-version":[{"id":265860,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts\/242406\/revisions\/265860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/media\/242410"}],"wp:attachment":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/media?parent=242406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/categories?post=242406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/tags?post=242406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}