{"id":242260,"date":"2017-07-03T00:00:00","date_gmt":"2017-07-02T23:00:00","guid":{"rendered":"https:\/\/www.procarton.com\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/"},"modified":"2021-11-05T18:29:12","modified_gmt":"2021-11-05T18:29:12","slug":"round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma","status":"publish","type":"post","link":"https:\/\/www.procarton.com\/de\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/","title":{"rendered":"Rundtischgespr\u00e4ch mit Roland Rex (Pr\u00e4sident Pro Carton) und Andreas Blaschke (Pr\u00e4sident ECMA)"},"content":{"rendered":"<p><em>1. Welche Erwartungen haben Sie f\u00fcr Ihre Branche in den n\u00e4chsten 12 Monaten?<br \/>\n<\/em><\/p>\n<p style=\"color: red;\">RR - Alle Indikatoren f\u00fcr den privaten Verbrauch in Europa sind positiv, so dass die Nachfrage nach FMCG-Verpackungen steigen wird. Dies wird dazu beitragen, einige der freien Produktionskapazit\u00e4ten zu f\u00fcllen. Das ver\u00e4nderte Einkaufsverhalten hin zu einem diversifizierten Omnichannel-Einkaufsumfeld und die Digitalisierung werden neue M\u00f6glichkeiten schaffen. Ich bin der Meinung, dass die Konsolidierung der Branche dazu beitragen wird, st\u00e4rkere, kosteneffizientere und innovativere Unternehmen zu schaffen, die die Anforderungen unserer Kunden erf\u00fcllen und vor allem rentabel sein k\u00f6nnen.<\/p>\n<p style=\"color: blue;\">AB - Das Volumen d\u00fcrfte im n\u00e4chsten Jahr gut sein, da die Wirtschaft wieder anzieht. Die Margen bleiben jedoch unter Druck, da die Rohstoffpreise gestiegen sind und sich nur schwer erholen lassen. Kurzfristig rechne ich nicht mit einer weiteren Konsolidierung oder Rationalisierung im gro\u00dfen Stil, da viele Unternehmen eine Phase des Wandels durchlaufen haben, auf die oft eine Phase der Integration und Stabilit\u00e4t folgt.<\/p>\n<p><em> 2. Was ist die gr\u00f6\u00dfte Herausforderung, mit der die Kartonindustrie derzeit konfrontiert ist?<\/em><\/p>\n<p style=\"color: blue;\">AB - Ich denke, es ist die Diskrepanz zwischen den Erwartungen der Kunden und den M\u00f6glichkeiten der Lieferkette. Die Vorlaufzeiten f\u00fcr Karton werden immer l\u00e4nger, w\u00e4hrend die Kartonkunden mehr Flexibilit\u00e4t und k\u00fcrzere Vorlaufzeiten w\u00fcnschen und es ablehnen, Betriebskapital auf Lager zu binden. Wir m\u00fcssen neue L\u00f6sungen finden, ohne zus\u00e4tzliche Kosten zu verursachen.<\/p>\n<p style=\"color: red;\">RR - Es gibt viele Herausforderungen, die unsere Branche betreffen. Viele davon sind gut und hilfreich und wir wollen nicht nachlassen, sondern das Tempo beibehalten, um besser zu werden. Aber es gibt eine Herausforderung, die gr\u00f6\u00dfer zu sein scheint als alle anderen. Das ist die schnell wachsende \u00dcberkapazit\u00e4t auf unserem Markt, der nur m\u00e4\u00dfig w\u00e4chst. Wir m\u00fcssen unsere Denkweise von \"mehr vom Gleichen\" auf \"das Gleiche besser machen\" \u00e4ndern. Dies ist ein ges\u00fcnderer Weg f\u00fcr Wachstum als nur \"mehr\".<\/p>\n<p><em> 3. Wie k\u00f6nnten Kartonverarbeiter und Kartonfabriken Ihrer Meinung nach besser zusammenarbeiten?<\/em><\/p>\n<p style=\"color: red;\">RR - Das Wichtigste ist zu verstehen, dass das eine vom anderen abh\u00e4ngt. Es gibt keine Kartons ohne Karton und umgekehrt. Es muss also eine positive und profitable Zusammenarbeit f\u00fcr beide Partner in der Lieferkette erreicht werden. Dies erfordert ein gewisses Ma\u00df an Offenheit und Vertrauen sowie die Bereitschaft, wirklich zusammenzuarbeiten, um das Gesch\u00e4ft gemeinsam auf profitable und innovative Weise zu entwickeln.<\/p>\n<p style=\"color: blue;\">AB - Wir m\u00fcssen einen Weg finden, unsere Lieferketten besser aufeinander abzustimmen und gleichzeitig die Kosten zu senken, und ich glaube, es gibt noch viele M\u00f6glichkeiten f\u00fcr uns, bei der Kostensenkung zusammenzuarbeiten. Au\u00dferdem k\u00f6nnten Verarbeiter und Papierfabriken bei der Entwicklung spezieller Platten f\u00fcr ausgew\u00e4hlte gro\u00dfe Endverbraucher st\u00e4rker zusammenarbeiten.<\/p>\n<p><em> 4. Was halten Sie von der st\u00e4ndigen negativen Publicity, die die Plastikindustrie in Bezug auf Abfall und Verschmutzung der Meere erh\u00e4lt?<\/em><\/p>\n<p style=\"color: blue;\">AB - Die Karton- und Faltschachtelindustrie hat wirklich eine gro\u00dfe Chance, ihre positiven Umwelteigenschaften deutlich zu machen, und muss ihre St\u00e4rken und Vorteile weiterhin kommunizieren. Es geht um nachhaltige Forstwirtschaft, erneuerbare Ressourcen, Kompostierbarkeit und einfache Wiederverwertbarkeit.<\/p>\n<p style=\"color: red;\">RR - Die Verbraucher - zumindest in Europa - beginnen zu verstehen, dass Verpackungen wichtig sind, aber dass Kunststoffverpackungen ein ernstes Problem f\u00fcr die Umwelt darstellen. Sie verstehen zu unterscheiden zwischen Verpackungen, die aus einem erneuerbaren oder recycelten Material hergestellt werden, und Verpackungen, die fossile Ressourcen verbrauchen und Fl\u00fcsse, Seen und Meere verschmutzen, und das nicht nur auf anderen Kontinenten. Dies ist eine gro\u00dfe Chance f\u00fcr Karton und Faltschachteln, sich als die nachhaltigste Verpackungsvariante zu positionieren, die einen doppelt positiven Effekt auf das Klima und die Wiederverwendung hat. Je \u00f6fter Plastik von den Meinungsf\u00fchrern kritisiert wird, desto besser f\u00fcr uns.<\/p>\n<p><em> 5. \u00c4ndern sich die Anforderungen der Markeninhaber und Einzelh\u00e4ndler?<\/em><\/p>\n<p style=\"color: red;\">RR - Die Bed\u00fcrfnisse der Einzelh\u00e4ndler und Markeninhaber haben sich schon immer ver\u00e4ndert. Der Unterschied ist jetzt die Geschwindigkeit des Wandels. Die Digitalisierung bestimmt unser Leben und ver\u00e4ndert unsere Gesch\u00e4ftsmodelle in rasantem Tempo, so dass es wichtig ist, in engem Kontakt mit denjenigen zu stehen, die auf dem Fahrersitz sitzen und uns dabei helfen, das Kommende vorherzusagen. Der Omnichannel-Einzelhandel mit individualisierten und personalisierten Verpackungen wird schnell kommen.<\/p>\n<p style=\"color: blue;\">AB - Die Nachfrage ist unbest\u00e4ndiger und weniger vorhersehbar geworden, und die Losgr\u00f6\u00dfen werden immer kleiner. Der Einzelhandel ver\u00e4ndert sich und verlagert sich mehr ins Internet. Einige unserer Kunden m\u00fcssen neue Wege finden, um auf diese M\u00f6glichkeiten zu reagieren, vor allem diejenigen, die in Kategorien von Impulsk\u00e4ufen t\u00e4tig sind, die online schwieriger zu vermarkten sind. Ich denke hier zum Beispiel an Produkte wie S\u00fc\u00dfwaren, die oft an den Kassen angeboten werden.<\/p>\n<p><em> 6. Sind Sie der Meinung, dass der Preis angesichts der st\u00e4ndigen Nutzung von elektronischen Ausschreibungen und Auktionen immer weniger ein Faktor bei Angebotsentscheidungen ist?<\/em><\/p>\n<p style=\"color: blue;\">AB: Der Preis ist nach wie vor ein wichtiger Faktor, und wir m\u00fcssen weiterhin nach M\u00f6glichkeiten suchen, die Kosten zu senken. Da kann man eine Menge tun. Was Ausschreibungen und elektronische Auktionen angeht, so sind sie inzwischen fest etabliert, und ich hoffe, dass die meisten Akteure ausreichend Erfahrung im Umgang mit ihnen haben, was vor 5 oder 7 Jahren noch nicht der Fall war.<\/p>\n<p style=\"color: red;\">RR - Der Preis war und wird immer ein wichtiger Aspekt bei der Kaufentscheidung sein. Deshalb m\u00fcssen wir st\u00e4ndig an Kostensenkungen in der gesamten Lieferkette von Karton arbeiten. Aber neue Wege der Produktwerbung werden neue M\u00f6glichkeiten f\u00fcr Verpackungen in Verbindung mit neuen Dienstleistungen f\u00fcr Kartonhersteller bieten. Wir m\u00fcssen wegkommen von einem \"Kosten plus x\"-Denken hin zu einem \"Was ist der Nutzen f\u00fcr meinen Kunden\", f\u00fcr den er bereit ist zu zahlen. Die Digitalisierung wird Flexibilit\u00e4t entlang der gesamten Verpackungslieferkette erfordern, was es uns erm\u00f6glichen wird, unsere Preispolitik zu \u00fcberpr\u00fcfen.<\/p>\n<p><em> 7. Wie wichtig ist Innovation in der Kartonindustrie?<\/em><\/p>\n<p style=\"color: blue;\">AB - Innovation steht ganz oben auf der Tagesordnung und ist eine gute M\u00f6glichkeit, sich von der Konkurrenz abzuheben. In der Praxis werden jedoch relativ wenige neue Ideen tats\u00e4chlich \u00fcbernommen und auf den Markt gebracht. Meiner Erfahrung nach ist echte Innovation am besten, wenn der Kartonverarbeiter eine bew\u00e4hrte und langfristige Gesch\u00e4ftsbeziehung hat und die Bed\u00fcrfnisse der Verbraucher wirklich versteht.<\/p>\n<p style=\"color: red;\">RR - Innovation ist das, was unsere Kunden von uns erwarten, und deshalb ist sie f\u00fcr die Zukunft unserer Unternehmen unerl\u00e4sslich. Urspr\u00fcnglich diente die Verpackung nur dazu, das Produkt vor Besch\u00e4digung oder Verlust zu sch\u00fctzen. Dann kamen die Marketingaspekte hinzu, so dass heute klar ist, dass die Verpackung eine wichtige Rolle bei der Kaufentscheidung des K\u00e4ufers spielt. Und in Zukunft wird die Verpackung zum Kommunikationsmittel in der gesamten Lieferkette, das unn\u00f6tige Kosten vermeidet und die Prozesszeiten verk\u00fcrzt.<\/p>\n<p><em> 8. Welche Auswirkungen haben die j\u00fcngsten und kommenden politischen Ver\u00e4nderungen auf die Branche und Ihr Unternehmen?<\/em><\/p>\n<p style=\"color: red;\">RR - Es gab und gibt immer wieder unerwartete Entwicklungen, die sich auf unsere Unternehmen auswirken - nicht nur politische. Wenn man also eine solide und breite Basis hat, kann man Zeiten der Unsicherheit leicht \u00fcberwinden. Und jedes Risiko bietet auch neue Chancen, man muss nur offen sein und positiv denken.<\/p>\n<p style=\"color: blue;\">AB - Die gr\u00f6\u00dften Auswirkungen hatten die Wechselkurse, die neue Herausforderungen mit sich brachten. Ansonsten glaube ich nicht, dass sich aus politischer Sicht f\u00fcr unsere Branche wirklich viel ge\u00e4ndert hat oder \u00e4ndern wird.<\/p>\n<p><em> 9. Wenn Sie eine Sache in der Branche \u00e4ndern k\u00f6nnten, was w\u00e4re das?<\/em><\/p>\n<p style=\"color: red;\">RR - Wir m\u00fcssen unsere Perspektive \u00e4ndern. Wir sollten nicht immer versuchen, die Welt aus unserer eigenen Position heraus zu verstehen und zu erkl\u00e4ren, sondern wir m\u00fcssen die Welt aus der Sicht unserer Kunden und der Kunden unserer Kunden verstehen, so dass wir wirklich Produkte und Dienstleistungen entwickeln, die unseren Kunden in ihrem Gesch\u00e4ftsumfeld helfen. Das wird sich positiv auf uns auswirken und uns unverzichtbar machen. Wenn wir uns weiterhin auf unsere eigenen Prozesse und internen Aktivit\u00e4ten konzentrieren, werden wir entweder immer hinterherhinken oder von denen ignoriert werden, die f\u00fcr uns wesentlich sind, n\u00e4mlich unseren Kunden.<\/p>\n<p style=\"color: blue;\">AB - Ich m\u00f6chte die Wahrnehmung unseres Produkts \u00e4ndern. Wir m\u00fcssen uns davon verabschieden, dass Verpackung nur ein Kostenfaktor ist, und sie als Mittel zur Wertsch\u00f6pfung betrachten. Eigentlich sind Kartons das beste Material f\u00fcr die Markenbildung eines jeden Produkts!<\/p>\n<p><em> 10. Haben Sie eine letzte Botschaft an Ihre Mitglieder?<\/em><\/p>\n<p style=\"color: red;\">RR - Ich stimme Andreas zu, dass wir den Menschen immer wieder sagen m\u00fcssen, dass Verpackung ein Wert und nicht nur ein Kostenfaktor ist, und dass Karton aufgrund seiner Nachhaltigkeitsvorteile die beste verf\u00fcgbare Option ist. Plastik ist f\u00fcr Verlierer - Karton ist f\u00fcr Gewinner, weil Karton keinen Plastikm\u00fcll verursacht.<\/p>\n<p style=\"color: blue;\">AB - Sie k\u00f6nnen darin lesen, was Sie wollen, aber meine Botschaft ist, jeder Versuchung zu widerstehen und nicht impulsiv zu sein.<\/p>\n<p><em> Ich danke Ihnen, meine Herren.<\/em><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Welche Erwartungen haben Sie f\u00fcr Ihre Branche in den n\u00e4chsten 12 Monaten?<br \/>\nRR - Alle Indikatoren f\u00fcr den privaten Verbrauch in Europa sind positiv, so dass die Nachfrage nach FMCG-Verpackungen steigen wird. Dies wird dazu beitragen, einige der freien Produktionskapazit\u00e4ten zu f\u00fcllen. Das ver\u00e4nderte Einkaufsverhalten hin zu einem diversifizierten Omnichannel-Einkaufsumfeld und die Digitalisierung werden neue M\u00f6glichkeiten schaffen. Ich bin der Meinung, dass die Konsolidierung der Branche dazu beitragen wird, st\u00e4rkere, kosteneffizientere und innovativere Unternehmen zu schaffen, die die Anforderungen unserer Kunden erf\u00fcllen und vor allem rentabel sein k\u00f6nnen.<br \/>\nAB - Das Volumen d\u00fcrfte im n\u00e4chsten Jahr gut sein, da die Wirtschaft wieder anzieht.  Die Margen bleiben jedoch unter Druck, da die Rohstoffpreise gestiegen sind und sich nur schwer erholen lassen.  Kurzfristig rechne ich nicht mit einer weiteren Konsolidierung oder Rationalisierung im gro\u00dfen Stil, da viele Unternehmen eine Phase des Wandels durchlaufen haben, auf die oft eine Phase der Integration und Stabilit\u00e4t folgt.<\/p>","protected":false},"author":1,"featured_media":242261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[79],"tags":[45],"class_list":["post-242260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brands-markets","tag-experts-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Round Table discussion with Roland Rex (President Pro Carton) and Andreas Blaschke (President ECMA) - Pro Carton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.procarton.com\/de\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Round Table discussion with Roland Rex (President Pro Carton) and Andreas Blaschke (President ECMA) - Pro Carton\" \/>\n<meta property=\"og:description\" content=\"What are your expectations for your industries over the next 12 months? RR - All indicators for private consumption are positive in Europe so the demand for FMCG packaging will grow. This will help to fill some of the spare production capacities. Changing shopping behaviour to a diversified omni-channel shopping environment and digitalization will both create new opportunities. I feel that industry consolidation will help create stronger, more cost efficient and innovative businesses which can fulfil our customers\u2019 requirements and, importantly, be profitable. AB \u2013 Volume should be good over the next year as the economy is picking up. Margins, however, remain under pressure since raw material prices are up and hard to recover. I don\u2019t expect to see much further consolidation or largescale rationalisation in the short term as many companies have been through a period of change which is often followed by a period of integration and stability.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.procarton.com\/de\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Carton\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/procartondesignaward\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-02T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-05T18:29:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/beide-praesidenten-home.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"esterling@admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:site\" content=\"@pro_carton\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"esterling@admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/\"},\"author\":{\"name\":\"esterling@admin\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\"},\"headline\":\"Round Table discussion with Roland Rex (President Pro Carton) and Andreas Blaschke (President ECMA)\",\"datePublished\":\"2017-07-02T23:00:00+00:00\",\"dateModified\":\"2021-11-05T18:29:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/\"},\"wordCount\":1407,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/beide-praesidenten-home.jpg\",\"keywords\":[\"Experts\"],\"articleSection\":[\"Brands &amp; Markets\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/\",\"name\":\"Round Table discussion with Roland Rex (President Pro Carton) and Andreas Blaschke (President ECMA) - Pro Carton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/beide-praesidenten-home.jpg\",\"datePublished\":\"2017-07-02T23:00:00+00:00\",\"dateModified\":\"2021-11-05T18:29:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/beide-praesidenten-home.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/beide-praesidenten-home.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.procarton.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Round Table discussion with Roland Rex (President Pro Carton) and Andreas Blaschke (President ECMA)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"name\":\"Pro Carton\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#organization\",\"name\":\"ProCarton\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"contentUrl\":\"https:\\\/\\\/www.procarton.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-mit-slogan.jpg\",\"width\":422,\"height\":519,\"caption\":\"ProCarton\"},\"image\":{\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/procartondesignaward\\\/\",\"https:\\\/\\\/x.com\\\/pro_carton\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.procarton.com\\\/es\\\/#\\\/schema\\\/person\\\/872a075145d2c38578ff4eed7d481251\",\"name\":\"esterling@admin\",\"sameAs\":[\"https:\\\/\\\/www.procarton.com\"],\"url\":\"https:\\\/\\\/www.procarton.com\\\/de\\\/author\\\/esterlingadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rundtischgespr\u00e4ch mit Roland Rex (Pr\u00e4sident Pro Carton) und Andreas Blaschke (Pr\u00e4sident ECMA) - Pro Carton","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.procarton.com\/de\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/","og_locale":"de_DE","og_type":"article","og_title":"Round Table discussion with Roland Rex (President Pro Carton) and Andreas Blaschke (President ECMA) - Pro Carton","og_description":"What are your expectations for your industries over the next 12 months? RR - All indicators for private consumption are positive in Europe so the demand for FMCG packaging will grow. This will help to fill some of the spare production capacities. Changing shopping behaviour to a diversified omni-channel shopping environment and digitalization will both create new opportunities. I feel that industry consolidation will help create stronger, more cost efficient and innovative businesses which can fulfil our customers\u2019 requirements and, importantly, be profitable. AB \u2013 Volume should be good over the next year as the economy is picking up. Margins, however, remain under pressure since raw material prices are up and hard to recover. I don\u2019t expect to see much further consolidation or largescale rationalisation in the short term as many companies have been through a period of change which is often followed by a period of integration and stability.","og_url":"https:\/\/www.procarton.com\/de\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/","og_site_name":"Pro Carton","article_publisher":"https:\/\/www.facebook.com\/procartondesignaward\/","article_published_time":"2017-07-02T23:00:00+00:00","article_modified_time":"2021-11-05T18:29:12+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/beide-praesidenten-home.jpg","type":"image\/jpeg"}],"author":"esterling@admin","twitter_card":"summary_large_image","twitter_creator":"@pro_carton","twitter_site":"@pro_carton","twitter_misc":{"Verfasst von":"esterling@admin","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/#article","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/"},"author":{"name":"esterling@admin","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251"},"headline":"Round Table discussion with Roland Rex (President Pro Carton) and Andreas Blaschke (President ECMA)","datePublished":"2017-07-02T23:00:00+00:00","dateModified":"2021-11-05T18:29:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/"},"wordCount":1407,"commentCount":0,"publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"image":{"@id":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/beide-praesidenten-home.jpg","keywords":["Experts"],"articleSection":["Brands &amp; Markets"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/","url":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/","name":"Rundtischgespr\u00e4ch mit Roland Rex (Pr\u00e4sident Pro Carton) und Andreas Blaschke (Pr\u00e4sident ECMA) - Pro Carton","isPartOf":{"@id":"https:\/\/www.procarton.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/#primaryimage"},"image":{"@id":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/beide-praesidenten-home.jpg","datePublished":"2017-07-02T23:00:00+00:00","dateModified":"2021-11-05T18:29:12+00:00","breadcrumb":{"@id":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/#primaryimage","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/beide-praesidenten-home.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2021\/02\/beide-praesidenten-home.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.procarton.com\/es\/round-table-discussion-with-roland-rex-president-pro-carton-and-andreas-blaschke-president-ecma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.procarton.com\/"},{"@type":"ListItem","position":2,"name":"Round Table discussion with Roland Rex (President Pro Carton) and Andreas Blaschke (President ECMA)"}]},{"@type":"WebSite","@id":"https:\/\/www.procarton.com\/es\/#website","url":"https:\/\/www.procarton.com\/es\/","name":"Pro Carton","description":"","publisher":{"@id":"https:\/\/www.procarton.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.procarton.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.procarton.com\/es\/#organization","name":"ProCarton","url":"https:\/\/www.procarton.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","contentUrl":"https:\/\/www.procarton.com\/wp-content\/uploads\/2022\/06\/logo-mit-slogan.jpg","width":422,"height":519,"caption":"ProCarton"},"image":{"@id":"https:\/\/www.procarton.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/procartondesignaward\/","https:\/\/x.com\/pro_carton"]},{"@type":"Person","@id":"https:\/\/www.procarton.com\/es\/#\/schema\/person\/872a075145d2c38578ff4eed7d481251","name":"esterling@admin","sameAs":["https:\/\/www.procarton.com"],"url":"https:\/\/www.procarton.com\/de\/author\/esterlingadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts\/242260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/comments?post=242260"}],"version-history":[{"count":1,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts\/242260\/revisions"}],"predecessor-version":[{"id":265899,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/posts\/242260\/revisions\/265899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/media\/242261"}],"wp:attachment":[{"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/media?parent=242260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/categories?post=242260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.procarton.com\/de\/wp-json\/wp\/v2\/tags?post=242260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}